{"id":21247,"date":"2024-02-08T14:01:28","date_gmt":"2024-02-08T14:01:28","guid":{"rendered":"https:\/\/pre.scenicrights.com\/projects\/saga-del-inspector-toure-serie-tv\/"},"modified":"2024-09-26T11:47:31","modified_gmt":"2024-09-26T11:47:31","slug":"saga-del-inspector-toure-serie-tv","status":"publish","type":"articulo","link":"https:\/\/www.scenicrights.com\/ca\/projects\/saga-del-inspector-toure-serie-tv\/","title":{"rendered":"Saga del Inspector Tour\u00e9 (Serie TV)"},"template":"","art_tag":[821,825,833,891,967,1073,1151],"genero":[46],"licencia":[17],"localizacion":[],"produccion":[16],"subgenero":[661],"tipo":[5],"class_list":["post-21247","articulo","type-articulo","status-publish","has-post-thumbnail","hentry","art_tag-detectiu","art_tag-diferencia-classe","art_tag-discriminacio","art_tag-familia-ca","art_tag-investigacio","art_tag-pobresa","art_tag-societat","genero-drama-ca","licencia-propia","produccion-explotacion","subgenero-policiac","tipo-proyecto"],"acf":{"generos_tax":[46],"subgeneros_tax":[661],"tipo_tax":[5],"tags_tax":[821,825,833,891,967,1073,1151],"produccion_tax":16,"licencia_tax":17,"localizacion_tax":false,"articulo__titulo_extendido":"","articulo__extracto":"","articulo__contenido":"https:\/\/www.youtube.com\/watch?v=UD0dH5c5Ihk\r\n<p align=\"center\"><strong>19 c\u00e1maras<\/strong><strong> | 612 euros | Sombras de la nada<\/strong><\/p>\r\n<p align=\"center\"><strong>Juegos de cloaca<\/strong><strong> | Piel de topo | No digas nada<\/strong><\/p>\r\nTour\u00e9 es un inmigrante ilegal de Burkina Faso que vive en San Francisco, el barrio marginal del centro de Bilbao \u2013com\u00fanmente conocido como \u201cPeque\u00f1a \u00c1frica\u201d-. Para Tour\u00e9 es una lucha diaria sobrevivir en un barrio que, pese a su colorido y diversidad y que le da acogida y refugio, abunda la criminalidad, la prostituci\u00f3n y la mala vida de las clases m\u00e1s humildes.\r\n\r\nA pesar de ganarse la vida (malamente) como supuesto vidente y gigol\u00f3, Tour\u00e9 acepta un peque\u00f1o trabajo que le encarga su conocida Charo: iniciarse como detective privado, investigando la doble vida de su marido. Esta aventura atrae a Tour\u00e9 m\u00e1s de lo que pensaba, hasta el punto de meterse de lleno en el mundo de la investigaci\u00f3n.\r\n\r\nTour\u00e9 es muy conocido en el barrio y, junto a sus amigos, se har\u00e1 cargo de diversos casos, como asesinatos a sangre fr\u00eda, amenazas a manos de la polic\u00eda local, o desapariciones misteriosas de conocidos de San Francisco.\r\n\r\nPero Tour\u00e9, como cualquier inmigrante sin papeles, tiene m\u00e1s preocupaciones que le quitan el sue\u00f1o: quiere retomar la relaci\u00f3n con su hija, que vive en Francia, y que terminar\u00e1 desapareciendo a manos de la mafia nigeriana, y tambi\u00e9n tendr\u00e1 que aprender a lidiar con su mujer Mariam, que, desde Burkina Faso, ans\u00eda con o reunirse de nuevo con su familia en su pa\u00eds, o conseguir los papeles para entrar en Europa. Adem\u00e1s, Tour\u00e9 tendr\u00e1 que mantener oculta su relaci\u00f3n amorosa con Cristina (o Sa Ken\u00e9, como la llama \u00e9l), una prostituta del barrio de la que se queda prendado.\r\n\r\nTras un tiempo en Espa\u00f1a, Tour\u00e9 es deportado a Mali (total, que m\u00e1s da Mali que Burkina Faso); consigue volver a su barrio de San Francisco; y despu\u00e9s de tener que enfrentarse a la corrupci\u00f3n de la polic\u00eda local, terminar\u00e1 por exiliarse en un pueblo del Pirineo navarro en busca de paz y tranquilidad. Pero en esa villa alejada de la mano de Dios nadie es quien dice ser, e incluso all\u00ed, Tour\u00e9 seguir\u00e1 desempe\u00f1ando su trabajo como detective.\r\n\r\nEl inspector Tour\u00e9 siempre actuar\u00e1 con ayuda de sus fieles amigos de la Peque\u00f1a \u00c1frica; Txema, el repartidor y amigo de juerga; Osman, su compa\u00f1ero de piso; o Adama, su compa\u00f1ero de patera. Con ellos, Tour\u00e9 aprender\u00e1 a superar todos los obst\u00e1culos que le plantea la vida, e intentar\u00e1 dejar de ser un sin papeles m\u00e1s.\r\n\r\n&nbsp;\r\n\r\n<strong>DATOS RELEVANTES<\/strong>: La saga del Inspector Tour\u00e9 est\u00e1 compuesta por seis entregas: <em>19 c\u00e1maras<\/em>, <em>612 euros<\/em>, <em>Sombras de la nada<\/em>, <em>Juegos de cloaca<\/em>, <em>Piel de topo<\/em>, y <em>No digas nada<\/em>. Todas ellas han recibido excelentes cr\u00edticas, que aseguran que Arretxe narra a la perfecci\u00f3n la situaci\u00f3n de los sectores m\u00e1s marginalizados de nuestra sociedad. Arretxe contrarresta las situaciones de gran crudeza y dramatismo con toques de humor y optimismo, gracias a personajes y situaciones hilarantes, muy bien construidos, sin caer en caricatura ni la banalidad.\r\n\r\n&nbsp;\r\n\r\nLo que dice la critica:\r\n\r\n\u201cPara los que creen que ya han visto todo en lo que a detectives se refiere, se equivocan: les falta Tour\u00e9.\u201d <em>Lectura en negro<\/em>\r\n\r\n\u201cTour\u00e9 es un personaje necesario y no \u00e9ramos conscientes de ello.\u201d revista <em>Calibre 38<\/em>\r\n\r\nJon Arretxe es un escritor vasco de novela negra y de libros de viajes. Sus obras han sido muy bien acogidas por parte del p\u00fablico y la cr\u00edtica, que lo posicionan entre uno de los mejores autores del Pa\u00eds Vasco hasta el momento.\r\n\r\n&nbsp;\r\n\r\n<strong>POTENCIAL AUDIOVISUAL<\/strong>: En desarrollo para formato serie TV.\r\n\r\n<strong>IDIOMAS DISPONIBLES:<\/strong> Espa\u00f1ol, Ingl\u00e9s, Euskera.","articulo__autor":[2901],"_thumbnail_id":23225,"articulo__featured_gallery":"","articulo__galeria_archivos":"","articulo__fecha_de_publicacion":"","articulo__idiomas":"","articulo__dossier":"","idarticle":1319},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Saga del Inspector Tour\u00e9 (Serie TV) - Scenic\u00a0Rights<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.scenicrights.com\/ca\/projects\/saga-del-inspector-toure-serie-tv\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Saga del Inspector Tour\u00e9 (Serie TV) - Scenic\u00a0Rights\" \/>\n<meta property=\"og:description\" content=\"19 c&aacute;maras | 612 euros | Sombras de la nada Juegos de cloaca | Piel de topo | No digas nada Tour&eacute; es un inmigrante ilegal [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.scenicrights.com\/ca\/projects\/saga-del-inspector-toure-serie-tv\/\" \/>\n<meta property=\"og:site_name\" content=\"Scenic\u00a0Rights\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-26T11:47:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2023\/09\/1705920124653.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"1142\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/projects\\\/saga-del-inspector-toure-serie-tv\\\/\",\"url\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/projects\\\/saga-del-inspector-toure-serie-tv\\\/\",\"name\":\"Saga del Inspector Tour\u00e9 (Serie TV) - Scenic\u00a0Rights\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/projects\\\/saga-del-inspector-toure-serie-tv\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/projects\\\/saga-del-inspector-toure-serie-tv\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.scenicrights.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/1705920124653.jpeg\",\"datePublished\":\"2024-02-08T14:01:28+00:00\",\"dateModified\":\"2024-09-26T11:47:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/projects\\\/saga-del-inspector-toure-serie-tv\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/projects\\\/saga-del-inspector-toure-serie-tv\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/projects\\\/saga-del-inspector-toure-serie-tv\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.scenicrights.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/1705920124653.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.scenicrights.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/1705920124653.jpeg\",\"width\":800,\"height\":1142},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/projects\\\/saga-del-inspector-toure-serie-tv\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Saga del Inspector Tour\u00e9 (Serie TV)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/\",\"name\":\"Scenic\u00a0Rights\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/#organization\",\"name\":\"Scenic\u00a0Rights\",\"url\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.scenicrights.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logo-horizontal-web.png\",\"contentUrl\":\"https:\\\/\\\/www.scenicrights.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logo-horizontal-web.png\",\"width\":644,\"height\":225,\"caption\":\"Scenic\u00a0Rights\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Saga del Inspector Tour\u00e9 (Serie TV) - Scenic\u00a0Rights","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.scenicrights.com\/ca\/projects\/saga-del-inspector-toure-serie-tv\/","og_locale":"ca_ES","og_type":"article","og_title":"Saga del Inspector Tour\u00e9 (Serie TV) - Scenic\u00a0Rights","og_description":"19 c&aacute;maras | 612 euros | Sombras de la nada Juegos de cloaca | Piel de topo | No digas nada Tour&eacute; es un inmigrante ilegal [&hellip;]","og_url":"https:\/\/www.scenicrights.com\/ca\/projects\/saga-del-inspector-toure-serie-tv\/","og_site_name":"Scenic\u00a0Rights","article_modified_time":"2024-09-26T11:47:31+00:00","og_image":[{"width":800,"height":1142,"url":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2023\/09\/1705920124653.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.scenicrights.com\/ca\/projects\/saga-del-inspector-toure-serie-tv\/","url":"https:\/\/www.scenicrights.com\/ca\/projects\/saga-del-inspector-toure-serie-tv\/","name":"Saga del Inspector Tour\u00e9 (Serie TV) - Scenic\u00a0Rights","isPartOf":{"@id":"https:\/\/www.scenicrights.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.scenicrights.com\/ca\/projects\/saga-del-inspector-toure-serie-tv\/#primaryimage"},"image":{"@id":"https:\/\/www.scenicrights.com\/ca\/projects\/saga-del-inspector-toure-serie-tv\/#primaryimage"},"thumbnailUrl":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2023\/09\/1705920124653.jpeg","datePublished":"2024-02-08T14:01:28+00:00","dateModified":"2024-09-26T11:47:31+00:00","breadcrumb":{"@id":"https:\/\/www.scenicrights.com\/ca\/projects\/saga-del-inspector-toure-serie-tv\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.scenicrights.com\/ca\/projects\/saga-del-inspector-toure-serie-tv\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.scenicrights.com\/ca\/projects\/saga-del-inspector-toure-serie-tv\/#primaryimage","url":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2023\/09\/1705920124653.jpeg","contentUrl":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2023\/09\/1705920124653.jpeg","width":800,"height":1142},{"@type":"BreadcrumbList","@id":"https:\/\/www.scenicrights.com\/ca\/projects\/saga-del-inspector-toure-serie-tv\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.scenicrights.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Saga del Inspector Tour\u00e9 (Serie TV)"}]},{"@type":"WebSite","@id":"https:\/\/www.scenicrights.com\/ca\/#website","url":"https:\/\/www.scenicrights.com\/ca\/","name":"Scenic\u00a0Rights","description":"","publisher":{"@id":"https:\/\/www.scenicrights.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.scenicrights.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.scenicrights.com\/ca\/#organization","name":"Scenic\u00a0Rights","url":"https:\/\/www.scenicrights.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.scenicrights.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2023\/07\/logo-horizontal-web.png","contentUrl":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2023\/07\/logo-horizontal-web.png","width":644,"height":225,"caption":"Scenic\u00a0Rights"},"image":{"@id":"https:\/\/www.scenicrights.com\/ca\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/articulo\/21247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/articulo"}],"about":[{"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/types\/articulo"}],"acf:post":[{"embeddable":true,"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/autor\/2901"}],"acf:term":[{"embeddable":true,"taxonomy":"licencia","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/licencia\/17"},{"embeddable":true,"taxonomy":"produccion","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/produccion\/16"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/1151"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/1073"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/967"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/891"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/833"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/825"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/821"},{"embeddable":true,"taxonomy":"tipo","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/tipo\/5"},{"embeddable":true,"taxonomy":"subgenero","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/subgenero\/661"},{"embeddable":true,"taxonomy":"genero","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/genero\/46"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/media\/23225"}],"wp:attachment":[{"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/media?parent=21247"}],"wp:term":[{"taxonomy":"art_tag","embeddable":true,"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag?post=21247"},{"taxonomy":"genero","embeddable":true,"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/genero?post=21247"},{"taxonomy":"licencia","embeddable":true,"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/licencia?post=21247"},{"taxonomy":"localizacion","embeddable":true,"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/localizacion?post=21247"},{"taxonomy":"produccion","embeddable":true,"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/produccion?post=21247"},{"taxonomy":"subgenero","embeddable":true,"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/subgenero?post=21247"},{"taxonomy":"tipo","embeddable":true,"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/tipo?post=21247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}