{"id":26563,"date":"2024-09-02T10:18:46","date_gmt":"2024-09-02T10:18:46","guid":{"rendered":"https:\/\/www.scenicrights.com\/projects\/saga-loca-seduccion\/"},"modified":"2026-01-27T10:54:40","modified_gmt":"2026-01-27T10:54:40","slug":"saga-loca-seduccion","status":"publish","type":"articulo","link":"https:\/\/www.scenicrights.com\/ca\/projects\/saga-loca-seduccion\/","title":{"rendered":"Saga Loca Seducci\u00f3n"},"template":"","art_tag":[1291,696,699,703,705,845,891,953,859,1005,1127,1183,1195,1213],"genero":[46],"licencia":[],"localizacion":[],"produccion":[],"subgenero":[637,1404,675],"tipo":[5],"class_list":["post-26563","articulo","type-articulo","status-publish","has-post-thumbnail","hentry","art_tag-adiccio","art_tag-alcoholisme","art_tag-amistat","art_tag-amor-ca","art_tag-amor-impossible","art_tag-drogues","art_tag-familia-ca","art_tag-infidelitat","art_tag-malaltia","art_tag-matrimoni","art_tag-secrets","art_tag-triangle-amoros","art_tag-viatge","art_tag-violencia-ca","genero-drama-ca","subgenero-erotic","subgenero-romanc","subgenero-thriller-ca","tipo-proyecto"],"acf":{"generos_tax":[46],"subgeneros_tax":[675,1404,637],"tipo_tax":[5],"tags_tax":[703,705,1195,1291,1127,859,699,953,1183,1005,845,696,1213,891],"produccion_tax":false,"licencia_tax":false,"localizacion_tax":false,"articulo__titulo_extendido":"","articulo__extracto":"","articulo__contenido":"<p style=\"text-align: center;\"><strong>Oto\u00f1o en Manhattan | Quiero ser tu principio y tu fin | Recu\u00e9rdame | Sin mirar atr\u00e1s | Alguien inesperado<\/strong><\/p>\r\n<p style=\"text-align: right;\"><strong><em>En Manhattan, la seducci\u00f3n no sigue reglas.<\/em><\/strong><\/p>\r\n<em>Loca seducci\u00f3n<\/em> es una potente saga melodram\u00e1tica compuesta de cinco libros y un amplio elenco de personajes.\r\n\r\nEn <strong><em>Oto\u00f1o en Manhattan<\/em><\/strong> conocemos a Gabriel G\u00f3mez, protagonista de la primera parte de la saga. Gabriel es un exitoso arquitecto de Barcelona, cuyas habilidades naturales para la seducci\u00f3n lo han convertido en un hombre rodeado de pretendientes. Pero hay una mujer por la que se siente especialmente atra\u00eddo: Jessica Orson, su autoritaria, demandante y atractiva jefa que trabaja en la sede de la compa\u00f1\u00eda en Manhattan. Ambos son esc\u00e9pticos en el amor y mantienen una relaci\u00f3n puramente f\u00edsica cada vez que coinciden en viajes de trabajo. Gabriel, quien por su parte est\u00e1 intentando olvidar una relaci\u00f3n que hab\u00eda mantenido en secreto con la prometida de su hermano Iv\u00e1n, aprovecha un ascenso para trasladarse a Manhattan. Una parte de \u00e9l se alegra por estar m\u00e1s cerca de J\u00e9ssica, pero nada m\u00e1s aterrizar conoce a Daniela, su vecina, una chica joven y dulce. En seguida forjan una fuerte conexi\u00f3n. Daniela tambi\u00e9n se enreda en un juego de tensiones con Erick, un hombre atrapado en un matrimonio infeliz, adicto a las mujeres y apoyo incondicional de Gabriel. Gabriel se ver\u00e1 en conflicto entre las dos mujeres, dilema que empeora cuando a Jessica le diagnostican un c\u00e1ncer.\r\n\r\nEn <strong><em>Quiero ser tu principio y tu fin<\/em><\/strong> han pasado tres semanas desde de que Jessica se ha sometido a un trasplante para combatir su enfermedad, y decide mudarse con Gabriel a un apartamento peque\u00f1o para empezar una nueva vida. Pero Daniela regresa a su vida con un sorprendente secreto que hace tambalear la relaci\u00f3n: confiesa que es la hija secreta de J\u00e9ssica.\r\n\r\nEn <strong><em>Recu\u00e9rdame<\/em><\/strong>, conocemos a Noah Anderson, protagonista de la segunda mitad de la saga, amiga \u00edntima de Gabriel, que est\u00e1 casada con Clive Wilson, un hombre celoso, posesivo y maltratador que hace de su vida un infierno. Una noche, encuentran a Noah en un callej\u00f3n de Manhattan, herida de bala e inconsciente. Cuando despierta dos semanas despu\u00e9s, descubren que sufre de amnesia y no recuerda lo que sucedi\u00f3. Clive se convierte en el principal sospechoso de crimen. Con la ayuda de Colin, un atractivo neurocirujano y hermano de Clive, Noah comienza a recuperar su memoria y a recordar lo que sucedi\u00f3. Al mismo tiempo, Frank Evans, un amigo que la apoy\u00f3 en sus momentos m\u00e1s oscuros, est\u00e1 dispuesto a hacer lo que sea necesario para conseguir que Noah se enamore de \u00e9l.\r\n\r\nEn <strong><em>Sin mirar atr\u00e1s<\/em><\/strong>, Noah todav\u00eda sigue recuper\u00e1ndose de la terrible experiencia que ha vivido y debe enfrentarse a la verdad que esconde su marido, pues \u00e9ste forma parte de un c\u00edrculo de crimen organizado. Noah se deja llevar por la atracci\u00f3n que siente por Colin, con quien empezar\u00e1 un tri\u00e1ngulo amoroso junto con su marido. Al mismo tiempo, Gabriel G\u00f3mez se debate entre seguir o no con Jessica.\r\n\r\nEn <strong><em>Alguien inesperado<\/em><\/strong>, Colin Wilde est\u00e1 decidido a dejar atr\u00e1s su vida y su pasado en Manhattan tras verse envuelto en una complicada relaci\u00f3n con Noah, y decide regresar a su Irlanda natal. Al llegar conoce a Emma Campbell, quien le hace sentir cosas que no hab\u00eda sentido en mucho tiempo. Pero Emma tambi\u00e9n tiene sus propios secretos que no se atreve a confesar.\r\n\r\n&nbsp;\r\n\r\n<strong>DATOS RELEVANTES:<\/strong>\r\n\r\nLa S<em>aga Loca Seducci\u00f3n<\/em> ha vendido decenas de miles de ejemplares en distintas plataformas online.\r\n\r\nEva P. Valencia ha sido reconocida con numerosos premios, como el <strong>Wattys Wattpad en la categor\u00eda New adult<\/strong>, <strong>Mejor novela de Navidad<\/strong> por El Mundo, <strong>Premio Autor Revelaci\u00f3n de Bookstagrammer Lecturas Francy<\/strong> y <strong>finalista en la categor\u00eda de novela rom\u00e1ntica en el Evento Book\u2019s Wings BCN<\/strong>.\r\n\r\n&nbsp;\r\n\r\nLa saga cuenta con rese\u00f1as muy positivas:\r\n\r\n\"Eva P. Valencia consigue mantener al lector en una constante tensi\u00f3n, conteniendo el aliento y sin ning\u00fan tipo de tregua\". - <em>Amazon<\/em>\r\n\r\n\"Eva sabe conducir el hilo de la historia a la perfecci\u00f3n, resolviendo las tramas una a una, pero manteni\u00e9ndonos en vilo casi hasta el final\" - <em>Amazon<\/em>\r\n\r\n&nbsp;\r\n\r\n<strong>POTENCIAL AUDIOVISUAL:<\/strong> Serie TV, Miniserie, Film, TV Film.\r\n\r\n<strong>IDIOMAS DISPONIBLES:<\/strong> Espa\u00f1ol.","articulo__autor":[26236],"_thumbnail_id":26605,"articulo__featured_gallery":null,"articulo__galeria_archivos":"","articulo__fecha_de_publicacion":"","articulo__idiomas":"","articulo__dossier":"","idarticle":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Saga Loca Seducci\u00f3n - Scenic\u00a0Rights<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.scenicrights.com\/ca\/projects\/saga-loca-seduccion\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Saga Loca Seducci\u00f3n - Scenic\u00a0Rights\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.scenicrights.com\/ca\/projects\/saga-loca-seduccion\/\" \/>\n<meta property=\"og:site_name\" content=\"Scenic\u00a0Rights\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-27T10:54:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2024\/09\/OTONO-EN-MANHATTAN.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/projects\\\/saga-loca-seduccion\\\/\",\"url\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/projects\\\/saga-loca-seduccion\\\/\",\"name\":\"Saga Loca Seducci\u00f3n - Scenic\u00a0Rights\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/projects\\\/saga-loca-seduccion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/projects\\\/saga-loca-seduccion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.scenicrights.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/OTONO-EN-MANHATTAN.jpg\",\"datePublished\":\"2024-09-02T10:18:46+00:00\",\"dateModified\":\"2026-01-27T10:54:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/projects\\\/saga-loca-seduccion\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/projects\\\/saga-loca-seduccion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/projects\\\/saga-loca-seduccion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.scenicrights.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/OTONO-EN-MANHATTAN.jpg\",\"contentUrl\":\"https:\\\/\\\/www.scenicrights.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/OTONO-EN-MANHATTAN.jpg\",\"width\":1000,\"height\":1500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/projects\\\/saga-loca-seduccion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Saga Loca Seducci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/\",\"name\":\"Scenic\u00a0Rights\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/#organization\",\"name\":\"Scenic\u00a0Rights\",\"url\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.scenicrights.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logo-horizontal-web.png\",\"contentUrl\":\"https:\\\/\\\/www.scenicrights.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logo-horizontal-web.png\",\"width\":644,\"height\":225,\"caption\":\"Scenic\u00a0Rights\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Saga Loca Seducci\u00f3n - Scenic\u00a0Rights","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.scenicrights.com\/ca\/projects\/saga-loca-seduccion\/","og_locale":"ca_ES","og_type":"article","og_title":"Saga Loca Seducci\u00f3n - Scenic\u00a0Rights","og_url":"https:\/\/www.scenicrights.com\/ca\/projects\/saga-loca-seduccion\/","og_site_name":"Scenic\u00a0Rights","article_modified_time":"2026-01-27T10:54:40+00:00","og_image":[{"width":1000,"height":1500,"url":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2024\/09\/OTONO-EN-MANHATTAN.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.scenicrights.com\/ca\/projects\/saga-loca-seduccion\/","url":"https:\/\/www.scenicrights.com\/ca\/projects\/saga-loca-seduccion\/","name":"Saga Loca Seducci\u00f3n - Scenic\u00a0Rights","isPartOf":{"@id":"https:\/\/www.scenicrights.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.scenicrights.com\/ca\/projects\/saga-loca-seduccion\/#primaryimage"},"image":{"@id":"https:\/\/www.scenicrights.com\/ca\/projects\/saga-loca-seduccion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2024\/09\/OTONO-EN-MANHATTAN.jpg","datePublished":"2024-09-02T10:18:46+00:00","dateModified":"2026-01-27T10:54:40+00:00","breadcrumb":{"@id":"https:\/\/www.scenicrights.com\/ca\/projects\/saga-loca-seduccion\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.scenicrights.com\/ca\/projects\/saga-loca-seduccion\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.scenicrights.com\/ca\/projects\/saga-loca-seduccion\/#primaryimage","url":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2024\/09\/OTONO-EN-MANHATTAN.jpg","contentUrl":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2024\/09\/OTONO-EN-MANHATTAN.jpg","width":1000,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/www.scenicrights.com\/ca\/projects\/saga-loca-seduccion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.scenicrights.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Saga Loca Seducci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/www.scenicrights.com\/ca\/#website","url":"https:\/\/www.scenicrights.com\/ca\/","name":"Scenic\u00a0Rights","description":"","publisher":{"@id":"https:\/\/www.scenicrights.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.scenicrights.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.scenicrights.com\/ca\/#organization","name":"Scenic\u00a0Rights","url":"https:\/\/www.scenicrights.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.scenicrights.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2023\/07\/logo-horizontal-web.png","contentUrl":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2023\/07\/logo-horizontal-web.png","width":644,"height":225,"caption":"Scenic\u00a0Rights"},"image":{"@id":"https:\/\/www.scenicrights.com\/ca\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/articulo\/26563","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/articulo"}],"about":[{"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/types\/articulo"}],"acf:post":[{"embeddable":true,"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/autor\/26236"}],"acf:term":[{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/891"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/1213"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/696"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/845"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/1005"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/1183"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/953"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/699"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/859"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/1127"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/1291"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/1195"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/705"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/703"},{"embeddable":true,"taxonomy":"tipo","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/tipo\/5"},{"embeddable":true,"taxonomy":"subgenero","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/subgenero\/637"},{"embeddable":true,"taxonomy":"subgenero","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/subgenero\/1404"},{"embeddable":true,"taxonomy":"subgenero","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/subgenero\/675"},{"embeddable":true,"taxonomy":"genero","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/genero\/46"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/media\/26605"}],"wp:attachment":[{"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/media?parent=26563"}],"wp:term":[{"taxonomy":"art_tag","embeddable":true,"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag?post=26563"},{"taxonomy":"genero","embeddable":true,"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/genero?post=26563"},{"taxonomy":"licencia","embeddable":true,"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/licencia?post=26563"},{"taxonomy":"localizacion","embeddable":true,"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/localizacion?post=26563"},{"taxonomy":"produccion","embeddable":true,"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/produccion?post=26563"},{"taxonomy":"subgenero","embeddable":true,"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/subgenero?post=26563"},{"taxonomy":"tipo","embeddable":true,"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/tipo?post=26563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}