{"id":27055,"date":"2024-12-26T09:54:52","date_gmt":"2024-12-26T09:54:52","guid":{"rendered":"https:\/\/www.scenicrights.com\/projects\/saga-anna-y-vera\/"},"modified":"2026-04-28T10:44:24","modified_gmt":"2026-04-28T10:44:24","slug":"saga-anna-y-vera","status":"publish","type":"articulo","link":"https:\/\/www.scenicrights.com\/ca\/projects\/saga-anna-y-vera\/","title":{"rendered":"Saga Anna y Vera"},"template":"","art_tag":[699,703,705,815,839,891,953,967,1351,1045,1053,1423,1372,1115,1157],"genero":[46],"licencia":[17],"localizacion":[],"produccion":[],"subgenero":[657,1404,675],"tipo":[5],"class_list":["post-27055","articulo","type-articulo","status-publish","has-post-thumbnail","hentry","art_tag-amistat","art_tag-amor-ca","art_tag-amor-impossible","art_tag-desaparicio","art_tag-doble-vida-ca","art_tag-familia-ca","art_tag-infidelitat","art_tag-investigacio","art_tag-lgbtq-ca","art_tag-obsessio","art_tag-passat","art_tag-psicologico-ca","art_tag-relacio-toxica","art_tag-rivalitat","art_tag-suicidi","genero-drama-ca","licencia-propia","subgenero-misteri","subgenero-romanc","subgenero-thriller-ca","tipo-proyecto"],"acf":{"generos_tax":[46],"subgeneros_tax":[675,657,1404],"tipo_tax":[5],"tags_tax":[815,1423,705,967,953,699,703,839,891,1351,1045,1053,1372,1115,1157],"produccion_tax":false,"licencia_tax":17,"localizacion_tax":false,"articulo__titulo_extendido":"","articulo__extracto":"","articulo__contenido":"<strong><em>Entre desapariciones, asesinatos, relaciones clandestinas y secretos s\u00f3rdidos, estas novelas son un ejemplo perfecto de thriller con un fuerte componente dram\u00e1tico. Son verdaderos rompecabezas en los que los propios personajes, al desvelar sus secretos, muestran qui\u00e9nes son realmente.<\/em><\/strong>\r\n\r\n&nbsp;\r\n<p data-start=\"159\" data-end=\"613\">Anna Guirao es una famosa actriz espa\u00f1ola que desapareci\u00f3 el 19 de abril de 2019. Todos la dieron por muerta, pero en realidad fue secuestrada y encerrada en un zulo bajo tierra, en condiciones inhumanas. Trece meses m\u00e1s tarde, es encontrada desorientada en un bosque cercano al pueblo de Portella, L\u00e9rida. Tambi\u00e9n aparece el cad\u00e1ver del supuesto secuestrador, a pesar de que ella no recuerda haberlo matado ni siquiera haberlo visto durante su encierro.<\/p>\r\n<p data-start=\"615\" data-end=\"840\">Cuando llega a casa, descubre que todo es completamente distinto a como lo dej\u00f3: Adri\u00e1n, su marido, ha iniciado una relaci\u00f3n sentimental con su asistente, In\u00e9s, y ninguno de los dos parece demasiado emocionado por su regreso.<\/p>\r\n<p data-start=\"842\" data-end=\"1025\">Ni siquiera su hijo, Samuel, de ocho a\u00f1os, est\u00e1 de su lado, a pesar de que pensar en \u00e9l era lo que le daba fuerzas durante el secuestro. Solo Lara, su hermana, permanece junto a ella.<\/p>\r\n<p data-start=\"1027\" data-end=\"1261\">Se inicia una investigaci\u00f3n policial mientras los secretos que todos han tratado de mantener ocultos comienzan a salir a la luz: casi todos los protagonistas de la historia parecen tener una buena raz\u00f3n para querer deshacerse de Anna.<\/p>\r\n<p data-start=\"1263\" data-end=\"1621\">La situaci\u00f3n se complica a\u00fan m\u00e1s con la aparici\u00f3n de nuevas inc\u00f3gnitas: \u00bfqu\u00e9 relaci\u00f3n existe entre el secuestro de Anna y un homicidio en la carretera cuyo culpable nunca fue identificado? \u00bfQu\u00e9 conexi\u00f3n tiene ese asesinato con el esposo de Anna? \u00bfY qui\u00e9n es Martina, la novia de Lara, otra actriz que ocup\u00f3 el lugar de Anna en una famosa serie de televisi\u00f3n?<\/p>\r\n<p data-start=\"1623\" data-end=\"1685\">Todos parecen tener algo que ocultar, incluida la propia Anna.<\/p>\r\n<p data-start=\"1687\" data-end=\"1867\"><em><strong><span class=\"hover:entity-accent entity-underline inline cursor-pointer align-baseline\"><span class=\"whitespace-normal\">La mentira de Vera Ros<\/span><\/span><\/strong><\/em> es el segundo libro de la bilog\u00eda, aunque no comparte los mismos personajes, salvo la inspectora de polic\u00eda encargada de investigar los casos.<\/p>\r\n<p data-start=\"1869\" data-end=\"2420\">En esta entrega, Vera pasa el verano con su familia \u2014su esposo, el exitoso escritor Daniel Monz\u00f3n, y sus hijos\u2014 en una casa de la Costa Brava. Sin embargo, durante una de sus salidas matutinas a su cala favorita, se reencuentra con Alan, un amor de verano que cre\u00eda haber olvidado. Ambos comienzan a apoyarse mutuamente para enfrentar sus propios fantasmas: Alan lucha contra su tendencia autodestructiva y el dolor por la p\u00e9rdida de su esposa, mientras que Vera se siente atrapada en un matrimonio desgastado y en el asfixiante rol de esposa y madre.<\/p>\r\n<p data-start=\"2422\" data-end=\"2961\">La decepci\u00f3n de Vera hacia Daniel aumenta cuando encuentra un mensaje de su amante en su tel\u00e9fono. La situaci\u00f3n se intensifica cuando Vera y Alan descubren a Daniel con Patricia, su amante, en la cala. Los ven discutir y, al d\u00eda siguiente, Daniel desaparece. Pocos d\u00edas despu\u00e9s, aparece el cuerpo sin vida de Patricia, lo que convierte a Daniel en el principal sospechoso. Adem\u00e1s, un misterioso mensaje en su ordenador sugiere que alguien lo estaba amenazando. Daniel contacta con Vera, quien le asegura que no tiene intenci\u00f3n de regresar.<\/p>\r\n<p data-start=\"2963\" data-end=\"3361\">Mientras tanto, los secretos del pasado de Vera y Alan comienzan a salir a la luz. La relaci\u00f3n de Vera con Daniel se revela como lo que realmente es: una relaci\u00f3n t\u00f3xica, marcada por el abuso y el control. Vera y Alan se acercan cada vez m\u00e1s, aunque ella no est\u00e1 completamente segura de poder confiar en \u00e9l. Alan oculta un doloroso secreto, y Vera duda si est\u00e1 siendo sincero o si esconde algo m\u00e1s.<\/p>\r\n<p data-start=\"3363\" data-end=\"3656\">Pero lo que m\u00e1s le aterra a Vera es la posibilidad de que Daniel regrese. \u00bfEs realmente quien dice ser? \u00bfQu\u00e9 ocurrir\u00e1 si Vera decide dejarlo todo para perseguir sus sue\u00f1os junto a Alan? La verdad est\u00e1 rodeada de sombras, y el camino de Vera hacia la libertad ser\u00e1 tan peligroso como revelador.<\/p>\r\n&nbsp;\r\n\r\n<strong>DATOS RELEVANTES:<\/strong> En la saga de Anna y Vera, ambas historias est\u00e1n conectadas por la presencia de la misma inspectora de polic\u00eda que investiga los casos. Sin embargo, la parte procedural no ocupa un lugar central, ya que las novelas se enfocan m\u00e1s en las relaciones entre los personajes y en los conflictos que las rodean.\r\n\r\nAmbas novelas est\u00e1n construidas alternando el punto de vista de diversos personajes. Cada uno narra su parte de la historia, revelando sus propios secretos y a\u00f1adiendo nuevas piezas al complejo rompecabezas narrativo.\r\n\r\nLas rese\u00f1as y la cr\u00edtica dicen:\r\n\r\n\u201c<em>La verdad de Anna Guirao<\/em>\u00a0es un thriller convulso, un torbellino de mentiras y pasados ocultos que mantiene el inter\u00e9s lector desde el principio hasta el final\u201d. \u2013 <em>Mi rincon\u00edn de Lectura<\/em>\r\n\r\n\u201cEs una historia llena de sorpresas, personajes que dan mucho juego y una trama que engancha\u201d. \u2013 <em>Between Us<\/em> (blog literario)\r\n\r\n<strong>POTENCIAL AUDIOVISUAL:<\/strong> Serie TV, Miniserie, Film, TV Film.\r\n\r\n<strong>IDIOMAS DISPONIBLES:<\/strong> Espa\u00f1ol.","articulo__autor":[26867],"_thumbnail_id":27085,"articulo__featured_gallery":null,"articulo__galeria_archivos":"","articulo__fecha_de_publicacion":"","articulo__idiomas":"","articulo__dossier":"","idarticle":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Saga Anna y Vera - Scenic\u00a0Rights<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.scenicrights.com\/ca\/projects\/saga-anna-y-vera\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Saga Anna y Vera - Scenic\u00a0Rights\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.scenicrights.com\/ca\/projects\/saga-anna-y-vera\/\" \/>\n<meta property=\"og:site_name\" content=\"Scenic\u00a0Rights\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-28T10:44:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2024\/12\/814aQGsLS8L._UF10001000_QL80_-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/projects\\\/saga-anna-y-vera\\\/\",\"url\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/projects\\\/saga-anna-y-vera\\\/\",\"name\":\"Saga Anna y Vera - Scenic\u00a0Rights\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/projects\\\/saga-anna-y-vera\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/projects\\\/saga-anna-y-vera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.scenicrights.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/814aQGsLS8L._UF10001000_QL80_-1.jpg\",\"datePublished\":\"2024-12-26T09:54:52+00:00\",\"dateModified\":\"2026-04-28T10:44:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/projects\\\/saga-anna-y-vera\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/projects\\\/saga-anna-y-vera\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/projects\\\/saga-anna-y-vera\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.scenicrights.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/814aQGsLS8L._UF10001000_QL80_-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.scenicrights.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/814aQGsLS8L._UF10001000_QL80_-1.jpg\",\"width\":632,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/projects\\\/saga-anna-y-vera\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Saga Anna y Vera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/\",\"name\":\"Scenic\u00a0Rights\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/#organization\",\"name\":\"Scenic\u00a0Rights\",\"url\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.scenicrights.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logo-horizontal-web.png\",\"contentUrl\":\"https:\\\/\\\/www.scenicrights.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logo-horizontal-web.png\",\"width\":644,\"height\":225,\"caption\":\"Scenic\u00a0Rights\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Saga Anna y Vera - Scenic\u00a0Rights","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.scenicrights.com\/ca\/projects\/saga-anna-y-vera\/","og_locale":"ca_ES","og_type":"article","og_title":"Saga Anna y Vera - Scenic\u00a0Rights","og_url":"https:\/\/www.scenicrights.com\/ca\/projects\/saga-anna-y-vera\/","og_site_name":"Scenic\u00a0Rights","article_modified_time":"2026-04-28T10:44:24+00:00","og_image":[{"width":632,"height":1000,"url":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2024\/12\/814aQGsLS8L._UF10001000_QL80_-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.scenicrights.com\/ca\/projects\/saga-anna-y-vera\/","url":"https:\/\/www.scenicrights.com\/ca\/projects\/saga-anna-y-vera\/","name":"Saga Anna y Vera - Scenic\u00a0Rights","isPartOf":{"@id":"https:\/\/www.scenicrights.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.scenicrights.com\/ca\/projects\/saga-anna-y-vera\/#primaryimage"},"image":{"@id":"https:\/\/www.scenicrights.com\/ca\/projects\/saga-anna-y-vera\/#primaryimage"},"thumbnailUrl":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2024\/12\/814aQGsLS8L._UF10001000_QL80_-1.jpg","datePublished":"2024-12-26T09:54:52+00:00","dateModified":"2026-04-28T10:44:24+00:00","breadcrumb":{"@id":"https:\/\/www.scenicrights.com\/ca\/projects\/saga-anna-y-vera\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.scenicrights.com\/ca\/projects\/saga-anna-y-vera\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.scenicrights.com\/ca\/projects\/saga-anna-y-vera\/#primaryimage","url":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2024\/12\/814aQGsLS8L._UF10001000_QL80_-1.jpg","contentUrl":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2024\/12\/814aQGsLS8L._UF10001000_QL80_-1.jpg","width":632,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/www.scenicrights.com\/ca\/projects\/saga-anna-y-vera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.scenicrights.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Saga Anna y Vera"}]},{"@type":"WebSite","@id":"https:\/\/www.scenicrights.com\/ca\/#website","url":"https:\/\/www.scenicrights.com\/ca\/","name":"Scenic\u00a0Rights","description":"","publisher":{"@id":"https:\/\/www.scenicrights.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.scenicrights.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.scenicrights.com\/ca\/#organization","name":"Scenic\u00a0Rights","url":"https:\/\/www.scenicrights.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.scenicrights.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2023\/07\/logo-horizontal-web.png","contentUrl":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2023\/07\/logo-horizontal-web.png","width":644,"height":225,"caption":"Scenic\u00a0Rights"},"image":{"@id":"https:\/\/www.scenicrights.com\/ca\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/articulo\/27055","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/articulo"}],"about":[{"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/types\/articulo"}],"acf:post":[{"embeddable":true,"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/autor\/26867"}],"acf:term":[{"embeddable":true,"taxonomy":"licencia","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/licencia\/17"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/1157"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/1115"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/1372"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/1053"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/1045"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/1351"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/891"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/839"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/703"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/699"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/953"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/967"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/705"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/1423"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/815"},{"embeddable":true,"taxonomy":"tipo","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/tipo\/5"},{"embeddable":true,"taxonomy":"subgenero","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/subgenero\/1404"},{"embeddable":true,"taxonomy":"subgenero","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/subgenero\/657"},{"embeddable":true,"taxonomy":"subgenero","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/subgenero\/675"},{"embeddable":true,"taxonomy":"genero","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/genero\/46"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/media\/27085"}],"wp:attachment":[{"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/media?parent=27055"}],"wp:term":[{"taxonomy":"art_tag","embeddable":true,"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag?post=27055"},{"taxonomy":"genero","embeddable":true,"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/genero?post=27055"},{"taxonomy":"licencia","embeddable":true,"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/licencia?post=27055"},{"taxonomy":"localizacion","embeddable":true,"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/localizacion?post=27055"},{"taxonomy":"produccion","embeddable":true,"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/produccion?post=27055"},{"taxonomy":"subgenero","embeddable":true,"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/subgenero?post=27055"},{"taxonomy":"tipo","embeddable":true,"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/tipo?post=27055"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}