{"id":27705,"date":"2025-06-18T10:59:19","date_gmt":"2025-06-18T10:59:19","guid":{"rendered":"https:\/\/www.scenicrights.com\/projects\/sono-un-violin-en-paris\/"},"modified":"2025-07-02T11:38:20","modified_gmt":"2025-07-02T11:38:20","slug":"sono-un-violin-en-paris","status":"publish","type":"articulo","link":"https:\/\/www.scenicrights.com\/ca\/projects\/sono-un-violin-en-paris\/","title":{"rendered":"Son\u00f3 un viol\u00edn en Par\u00eds"},"template":"","art_tag":[699,703,715,803,813,839,873,879,1340,1351,1632,1031,1059,1061,1127,1151,1379,1195],"genero":[46],"licencia":[17],"localizacion":[],"produccion":[],"subgenero":[651,657,1404],"tipo":[5],"class_list":["post-27705","articulo","type-articulo","status-publish","has-post-thumbnail","hentry","art_tag-amistat","art_tag-amor-ca","art_tag-art","art_tag-cultura-ca","art_tag-desamor-ca","art_tag-doble-vida-ca","art_tag-espanya","art_tag-estafa-ca","art_tag-fets-reals","art_tag-lgbtq-ca","art_tag-mentiras-ca","art_tag-musica-ca","art_tag-paternitat","art_tag-periodisme","art_tag-secrets","art_tag-societat","art_tag-tragedia-ca","art_tag-viatge","genero-drama-ca","licencia-propia","subgenero-historic","subgenero-misteri","subgenero-romanc","tipo-proyecto"],"acf":{"generos_tax":[46],"subgeneros_tax":[651,657,1404],"tipo_tax":[5],"tags_tax":[1031,1127,1195,703,813,699,715,803,839,879,873,1340,1351,1632,1061,1059,1151,1379],"produccion_tax":false,"licencia_tax":17,"localizacion_tax":false,"articulo__titulo_extendido":"","articulo__extracto":"","articulo__contenido":"<em><strong>Un tren, algunos artistas y muchos secretos susurrados como chismes en un peri\u00f3dico. Un Gossip Girl ambientado en el Par\u00eds de finales del siglo XIX, donde el arte, el amor, el drama y el misterio se entrelazan en cada p\u00e1gina. De la mano de la autora bestseller Mar\u00eda Reig, una historia fascinante que nos transporta al coraz\u00f3n de una \u00e9poca brillante.<\/strong><\/em>\r\n\r\n&nbsp;\r\n\r\nEn el Par\u00eds de finales del siglo XIX, el c\u00e9lebre escritor Guillermo Bogar\u00edn lleva meses preparando un tour en tren por las principales ciudades de Europa junto a un grupo selecto, conformado por intelectuales y artistas. Aunque todos alardean de sus ansias de conocer mundo durante esos dos meses, lo cierto es que esta escapada tiene un motivo secreto para cada uno de los viajeros. Bogar\u00edn no invit\u00f3 a cada uno de ellos por casualidad. Para la sorpresa de todos, las pesquisas de su viaje y los secretos de cada uno ser\u00e1n publicadas en el peri\u00f3dico Le Petit Journal, en una nueva secci\u00f3n titulada \u201cLos diez de Bogar\u00edn\u201d, generando conflictos entre ellos\u2026\r\n\r\nCada cap\u00edtulo viene acompa\u00f1ado por una pieza musical, formando toda la novela una aut\u00e9ntica selecci\u00f3n de m\u00fasica cl\u00e1sica. Mar\u00eda Reig aborda temas universales como la necesidad de enfrentar los miedos, la importancia de tomar las riendas de la propia vida y las consecuencias de nuestras decisiones. Lo hace desde diversos puntos de vista, ya que cada viajero es m\u00e1s distinto del anterior, en profesi\u00f3n y car\u00e1cter: Jacobo Figueroa, un arquitecto deprimido de origen espa\u00f1ol; Juan \u00c1lvarez-Caballero, un ambicioso empresario tambi\u00e9n espa\u00f1ol y amigo de Jacobo; Ferdinard Mercier, un pintor impresionista franc\u00e9s; Jeanne Leroy, una empresaria teatral parisina que viaja junto a su sobrino de diecis\u00e9is a\u00f1os, Henri Collet; la condesa Karimova, una arist\u00f3crata rusa sumida en el duelo por la p\u00e9rdida de su hijo; y Gen\u00e8vieve Dupond, una empresaria francesa relacionada con el mundo de la m\u00fasica acompa\u00f1ada por su protegida, Clara Balaguer, una chica espa\u00f1ola virtuosa del viol\u00edn. Adem\u00e1s, en una de sus primeras paradas conocen a los hermanos Gustav y Thesi Pitcher, que pasan a acompa\u00f1arlos.\r\n\r\nAl principio, mientras pasean por Italia, el ambiente es distendido y divertido, algunos empiezan a trabar amistades e incluso sentimientos, pero seg\u00fan van llegando las revelaciones del peri\u00f3dico, todo se va complicando. Destaca por ejemplo el caso de Clara, uno de los personajes principales, cuando se publica que tuvo un antiguo amor que la dej\u00f3 mentalmente muy inestable y esto sale a la luz justo cuando se estaba acercando rom\u00e1nticamente a Jacobo. O el de Juan, en cuyo art\u00edculo se insin\u00faa que le atrae los hombres. De esta forma, est\u00e1 claro: hay un sopl\u00f3n entre ellos.\r\n\r\nDespu\u00e9s de conocerse que los hermanos Pitcher eran en realidad unos estafadores, se desvela la verdad: quien filtraba informaci\u00f3n al peri\u00f3dico era Henri Collet, el joven adolescente del grupo, que por algo de dinero hab\u00eda vendido p\u00fablicamente la vida de sus compa\u00f1eros de viaje. Henri ser\u00e1 desterrado por sus padres, sin saber si alg\u00fan d\u00eda podr\u00e1n perdonarlo.\r\n\r\nDespu\u00e9s de estas noticias, el grupo regresa a Par\u00eds, donde si para algo ha servido esta aventura desde luego es para acercar a Jacobo y Clara, pero el destino desgraciadamente tiene otros planes\u2026 Clara tiene la mala suerte de estar en el caf\u00e9 donde el anarquista \u00c9mile Henry (hecho real) llev\u00f3 a acabo un ataque con explosivos y la chica muere en el acto.\r\n\r\nTodos conocen la noticia y viven en paralelo un duelo por la muerte de la violinista, sobre todo Jacobo. Pero poco a poco, gracias a la memoria de Clara y lo que ha sentido por ella, re\u00fane el coraje suficiente como para buscar y luchar por la vida que quiere. As\u00ed, se marcha a Estados Unidos, con la m\u00fasica del viol\u00edn a\u00fan resonando en sus o\u00eddos.\r\n\r\n&nbsp;\r\n\r\n<strong>DATOS RELEVANTES:<\/strong> <em>Son\u00f3 un viol\u00edn en Par\u00eds<\/em> es una novela dram\u00e1tica que mezcla romance con melodrama y misterio. Recuerda a Agatha Christie por su coro de personajes reunidos en un lugar concreto, pero tambi\u00e9n a <em>Bridgerton<\/em> e incluso <em>Gossip Girl<\/em> por la presencia de un medio de comunicaci\u00f3n que revela sus intimidades.\r\n\r\nEsta novela plantea muchos temas, pero uno de los principales es sin duda la esperanza que hay tras el duelo, la posibilidad de seguir adelante a pesar de las dificultades. Otros grandes temas son el amor (tanto rom\u00e1ntico como familiar y de amistad) y el amor por la m\u00fasica y la cultura.\r\n\r\nSu autora Mar\u00eda Reig es una escritora especializada en novela hist\u00f3rica. Autopublic\u00f3 su primera novela y ya logr\u00f3 con ella considerables cifras de ventas. Con el conjunto de sus novelas, ha alcanzado los m\u00e1s de 100.000 ejemplares vendidos.\r\n\r\nLa cr\u00edtica y las rese\u00f1as dicen:\r\n\r\n\u201cUna novela tremendamente entretenida, donde el protagonismo coral aporta enredo a la trama mientras que la ambientaci\u00f3n hist\u00f3rica genera un fondo sobre el que dibujar una novela que se lee de una sentada.\u201d \u2013 <em>AhoraQu\u00e9Leo<\/em>\r\n\r\n\u201cEs incre\u00edble la capacidad que tiene Mar\u00eda Reig de transportarte en el tiempo.\u201d \u2013 La Casa del Libro\r\n\r\n\u201cEs muy interesante, adem\u00e1s, descubrir c\u00f3mo empez\u00f3 a gestarse, en esa \u00e9poca, el concepto de turismo, tal y como lo conocemos hoy en d\u00eda.\u201d\u00a0 - La Casa del Libro\r\n\r\n\u201cA trav\u00e9s de su amplio elenco de personajes, la historia es un fiel reflejo de la diversidad intelectual y cultural de la \u00e9poca, poniendo de manifiesto las transformaciones que estaban ocurriendo en la sociedad.\u201d - Goodreads\r\n\r\n&nbsp;\r\n\r\n<strong>POTENCIAL AUDIOVISUAL:<\/strong> Serie TV, Miniserie, Film, TV Film.\r\n\r\n<strong>IDIOMAS DISPONIBLES:<\/strong> Espa\u00f1ol.","articulo__autor":[27742],"_thumbnail_id":27703,"articulo__featured_gallery":null,"articulo__galeria_archivos":"","articulo__fecha_de_publicacion":"","articulo__idiomas":"","articulo__dossier":"","idarticle":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Son\u00f3 un viol\u00edn en Par\u00eds - Scenic\u00a0Rights<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.scenicrights.com\/ca\/projects\/sono-un-violin-en-paris\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Son\u00f3 un viol\u00edn en Par\u00eds - Scenic\u00a0Rights\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.scenicrights.com\/ca\/projects\/sono-un-violin-en-paris\/\" \/>\n<meta property=\"og:site_name\" content=\"Scenic\u00a0Rights\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-02T11:38:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2025\/06\/61OdTkLf1fL.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"689\" \/>\n\t<meta property=\"og:image:height\" content=\"1050\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/projects\\\/sono-un-violin-en-paris\\\/\",\"url\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/projects\\\/sono-un-violin-en-paris\\\/\",\"name\":\"Son\u00f3 un viol\u00edn en Par\u00eds - Scenic\u00a0Rights\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/projects\\\/sono-un-violin-en-paris\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/projects\\\/sono-un-violin-en-paris\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.scenicrights.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/61OdTkLf1fL.jpg\",\"datePublished\":\"2025-06-18T10:59:19+00:00\",\"dateModified\":\"2025-07-02T11:38:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/projects\\\/sono-un-violin-en-paris\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/projects\\\/sono-un-violin-en-paris\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/projects\\\/sono-un-violin-en-paris\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.scenicrights.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/61OdTkLf1fL.jpg\",\"contentUrl\":\"https:\\\/\\\/www.scenicrights.com\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/61OdTkLf1fL.jpg\",\"width\":689,\"height\":1050},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/projects\\\/sono-un-violin-en-paris\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Son\u00f3 un viol\u00edn en Par\u00eds\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/\",\"name\":\"Scenic\u00a0Rights\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/#organization\",\"name\":\"Scenic\u00a0Rights\",\"url\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.scenicrights.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logo-horizontal-web.png\",\"contentUrl\":\"https:\\\/\\\/www.scenicrights.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logo-horizontal-web.png\",\"width\":644,\"height\":225,\"caption\":\"Scenic\u00a0Rights\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Son\u00f3 un viol\u00edn en Par\u00eds - Scenic\u00a0Rights","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.scenicrights.com\/ca\/projects\/sono-un-violin-en-paris\/","og_locale":"ca_ES","og_type":"article","og_title":"Son\u00f3 un viol\u00edn en Par\u00eds - Scenic\u00a0Rights","og_url":"https:\/\/www.scenicrights.com\/ca\/projects\/sono-un-violin-en-paris\/","og_site_name":"Scenic\u00a0Rights","article_modified_time":"2025-07-02T11:38:20+00:00","og_image":[{"width":689,"height":1050,"url":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2025\/06\/61OdTkLf1fL.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.scenicrights.com\/ca\/projects\/sono-un-violin-en-paris\/","url":"https:\/\/www.scenicrights.com\/ca\/projects\/sono-un-violin-en-paris\/","name":"Son\u00f3 un viol\u00edn en Par\u00eds - Scenic\u00a0Rights","isPartOf":{"@id":"https:\/\/www.scenicrights.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.scenicrights.com\/ca\/projects\/sono-un-violin-en-paris\/#primaryimage"},"image":{"@id":"https:\/\/www.scenicrights.com\/ca\/projects\/sono-un-violin-en-paris\/#primaryimage"},"thumbnailUrl":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2025\/06\/61OdTkLf1fL.jpg","datePublished":"2025-06-18T10:59:19+00:00","dateModified":"2025-07-02T11:38:20+00:00","breadcrumb":{"@id":"https:\/\/www.scenicrights.com\/ca\/projects\/sono-un-violin-en-paris\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.scenicrights.com\/ca\/projects\/sono-un-violin-en-paris\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.scenicrights.com\/ca\/projects\/sono-un-violin-en-paris\/#primaryimage","url":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2025\/06\/61OdTkLf1fL.jpg","contentUrl":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2025\/06\/61OdTkLf1fL.jpg","width":689,"height":1050},{"@type":"BreadcrumbList","@id":"https:\/\/www.scenicrights.com\/ca\/projects\/sono-un-violin-en-paris\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.scenicrights.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Son\u00f3 un viol\u00edn en Par\u00eds"}]},{"@type":"WebSite","@id":"https:\/\/www.scenicrights.com\/ca\/#website","url":"https:\/\/www.scenicrights.com\/ca\/","name":"Scenic\u00a0Rights","description":"","publisher":{"@id":"https:\/\/www.scenicrights.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.scenicrights.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.scenicrights.com\/ca\/#organization","name":"Scenic\u00a0Rights","url":"https:\/\/www.scenicrights.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.scenicrights.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2023\/07\/logo-horizontal-web.png","contentUrl":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2023\/07\/logo-horizontal-web.png","width":644,"height":225,"caption":"Scenic\u00a0Rights"},"image":{"@id":"https:\/\/www.scenicrights.com\/ca\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/articulo\/27705","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/articulo"}],"about":[{"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/types\/articulo"}],"acf:post":[{"embeddable":true,"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/autor\/27742"}],"acf:term":[{"embeddable":true,"taxonomy":"licencia","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/licencia\/17"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/1379"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/1151"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/1059"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/1061"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/1632"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/1351"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/1340"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/873"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/879"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/839"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/803"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/715"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/699"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/813"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/703"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/1195"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/1127"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag\/1031"},{"embeddable":true,"taxonomy":"tipo","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/tipo\/5"},{"embeddable":true,"taxonomy":"subgenero","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/subgenero\/1404"},{"embeddable":true,"taxonomy":"subgenero","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/subgenero\/657"},{"embeddable":true,"taxonomy":"subgenero","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/subgenero\/651"},{"embeddable":true,"taxonomy":"genero","href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/genero\/46"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/media\/27703"}],"wp:attachment":[{"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/media?parent=27705"}],"wp:term":[{"taxonomy":"art_tag","embeddable":true,"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/art_tag?post=27705"},{"taxonomy":"genero","embeddable":true,"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/genero?post=27705"},{"taxonomy":"licencia","embeddable":true,"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/licencia?post=27705"},{"taxonomy":"localizacion","embeddable":true,"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/localizacion?post=27705"},{"taxonomy":"produccion","embeddable":true,"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/produccion?post=27705"},{"taxonomy":"subgenero","embeddable":true,"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/subgenero?post=27705"},{"taxonomy":"tipo","embeddable":true,"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/tipo?post=27705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}