{"id":2925,"date":"2023-09-12T13:17:23","date_gmt":"2023-09-12T13:17:23","guid":{"rendered":"https:\/\/pre.scenicrights.com\/author\/pablo-c-reyna\/"},"modified":"2024-04-17T22:05:14","modified_gmt":"2024-04-17T22:05:14","slug":"pablo-c-reyna","status":"publish","type":"autor","link":"https:\/\/www.scenicrights.com\/ca\/author\/pablo-c-reyna\/","title":{"rendered":"Pablo C. Reyna"},"template":"","class_list":["post-2925","autor","type-autor","status-publish","has-post-thumbnail","hentry"],"acf":{"autor_contenido":"<p style=\"text-align: right;\">\u00a0<strong><em>Scenic Rights is the audiovisual co-agency of Tormenta Libros Literary Agency.<\/em><\/strong><\/p>\r\nPablo C. Reyna (Espa\u00f1a, 1987) es escritor y editor especializado en literatura infantil y juvenil. Empez\u00f3 a colaborar desde muy joven en p\u00e1ginas web literarias del c\u00f3mic Bone, la serie Harry Potter o la escritora s\u00faper bestseller Laura Gallego, especializada en literatura juvenil.\r\n\r\nForm\u00f3 parte del equipo de la revista online El Templo de las Mil puertas, donde sigue participando espor\u00e1dicamente.\r\n\r\nHa publicado varios t\u00edtulos bajo seud\u00f3nimo con su equipo de Tormenta de libros, entre los que se encuentran <em>Vaya Cole<\/em> o la <em>Saga Bichos Raros.<\/em> <em>Multicosmos<\/em> es la primera obra que firma con su nombre, convirti\u00e9ndose tambi\u00e9n en su primera saga. Cuenta con cinco libros publicados adem\u00e1s de un web c\u00f3mic.\r\n\r\n&nbsp;\r\n\r\n<strong>INFORMACI\u00d3N RELEVANTE<\/strong>\r\n\r\nReyna es creador de la agencia literaria Tormenta. Ha sido <strong>finalista del Premio El Barco de Vapor<em>.<\/em><\/strong>\u00a0 La saga <em>Multicosmos<\/em> ha sido muy bien recibida en la comunidad online, donde Pablo C. Reyna goza de gran notoriedad en comunidades y foros literarios, utilizando el seud\u00f3nimo El Cronista de Salem.","_thumbnail_id":1759,"autor__galeria_archivos":[],"idauthor":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pablo C. Reyna - Scenic\u00a0Rights<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.scenicrights.com\/ca\/author\/pablo-c-reyna\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pablo C. Reyna - Scenic\u00a0Rights\" \/>\n<meta property=\"og:description\" content=\"&nbsp;Scenic Rights is the audiovisual co-agency of Tormenta Libros Literary Agency. Pablo C. Reyna (Espa&ntilde;a, 1987) es escritor y editor especializado en literatura infantil y juvenil. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.scenicrights.com\/ca\/author\/pablo-c-reyna\/\" \/>\n<meta property=\"og:site_name\" content=\"Scenic\u00a0Rights\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-17T22:05:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2023\/09\/Y2DCIlMo0WANZ0UFTPqQ.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/author\\\/pablo-c-reyna\\\/\",\"url\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/author\\\/pablo-c-reyna\\\/\",\"name\":\"Pablo C. Reyna - Scenic\u00a0Rights\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/author\\\/pablo-c-reyna\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/author\\\/pablo-c-reyna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.scenicrights.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Y2DCIlMo0WANZ0UFTPqQ.jpg\",\"datePublished\":\"2023-09-12T13:17:23+00:00\",\"dateModified\":\"2024-04-17T22:05:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/author\\\/pablo-c-reyna\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/author\\\/pablo-c-reyna\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/author\\\/pablo-c-reyna\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.scenicrights.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Y2DCIlMo0WANZ0UFTPqQ.jpg\",\"contentUrl\":\"https:\\\/\\\/www.scenicrights.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Y2DCIlMo0WANZ0UFTPqQ.jpg\",\"width\":1600,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/author\\\/pablo-c-reyna\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pablo C. Reyna\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/\",\"name\":\"Scenic\u00a0Rights\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/#organization\",\"name\":\"Scenic\u00a0Rights\",\"url\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.scenicrights.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logo-horizontal-web.png\",\"contentUrl\":\"https:\\\/\\\/www.scenicrights.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logo-horizontal-web.png\",\"width\":644,\"height\":225,\"caption\":\"Scenic\u00a0Rights\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pablo C. Reyna - Scenic\u00a0Rights","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.scenicrights.com\/ca\/author\/pablo-c-reyna\/","og_locale":"ca_ES","og_type":"article","og_title":"Pablo C. Reyna - Scenic\u00a0Rights","og_description":"&nbsp;Scenic Rights is the audiovisual co-agency of Tormenta Libros Literary Agency. Pablo C. Reyna (Espa&ntilde;a, 1987) es escritor y editor especializado en literatura infantil y juvenil. [&hellip;]","og_url":"https:\/\/www.scenicrights.com\/ca\/author\/pablo-c-reyna\/","og_site_name":"Scenic\u00a0Rights","article_modified_time":"2024-04-17T22:05:14+00:00","og_image":[{"width":1600,"height":1600,"url":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2023\/09\/Y2DCIlMo0WANZ0UFTPqQ.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.scenicrights.com\/ca\/author\/pablo-c-reyna\/","url":"https:\/\/www.scenicrights.com\/ca\/author\/pablo-c-reyna\/","name":"Pablo C. Reyna - Scenic\u00a0Rights","isPartOf":{"@id":"https:\/\/www.scenicrights.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.scenicrights.com\/ca\/author\/pablo-c-reyna\/#primaryimage"},"image":{"@id":"https:\/\/www.scenicrights.com\/ca\/author\/pablo-c-reyna\/#primaryimage"},"thumbnailUrl":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2023\/09\/Y2DCIlMo0WANZ0UFTPqQ.jpg","datePublished":"2023-09-12T13:17:23+00:00","dateModified":"2024-04-17T22:05:14+00:00","breadcrumb":{"@id":"https:\/\/www.scenicrights.com\/ca\/author\/pablo-c-reyna\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.scenicrights.com\/ca\/author\/pablo-c-reyna\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.scenicrights.com\/ca\/author\/pablo-c-reyna\/#primaryimage","url":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2023\/09\/Y2DCIlMo0WANZ0UFTPqQ.jpg","contentUrl":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2023\/09\/Y2DCIlMo0WANZ0UFTPqQ.jpg","width":1600,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/www.scenicrights.com\/ca\/author\/pablo-c-reyna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.scenicrights.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Pablo C. Reyna"}]},{"@type":"WebSite","@id":"https:\/\/www.scenicrights.com\/ca\/#website","url":"https:\/\/www.scenicrights.com\/ca\/","name":"Scenic\u00a0Rights","description":"","publisher":{"@id":"https:\/\/www.scenicrights.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.scenicrights.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/www.scenicrights.com\/ca\/#organization","name":"Scenic\u00a0Rights","url":"https:\/\/www.scenicrights.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/www.scenicrights.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2023\/07\/logo-horizontal-web.png","contentUrl":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2023\/07\/logo-horizontal-web.png","width":644,"height":225,"caption":"Scenic\u00a0Rights"},"image":{"@id":"https:\/\/www.scenicrights.com\/ca\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/autor\/2925","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/autor"}],"about":[{"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/types\/autor"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/media\/1759"}],"wp:attachment":[{"href":"https:\/\/www.scenicrights.com\/ca\/wp-json\/wp\/v2\/media?parent=2925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}