{"id":23595,"date":"2024-02-23T11:54:26","date_gmt":"2024-02-23T11:54:26","guid":{"rendered":"https:\/\/www.scenicrights.com\/?post_type=autor&#038;p=23595"},"modified":"2024-04-19T00:00:54","modified_gmt":"2024-04-19T00:00:54","slug":"anna-bonacina","status":"publish","type":"autor","link":"https:\/\/www.scenicrights.com\/en\/author\/anna-bonacina\/","title":{"rendered":"Anna Bonacina"},"template":"","class_list":["post-23595","autor","type-autor","status-publish","has-post-thumbnail","hentry"],"acf":{"autor_contenido":"<p style=\"text-align: right;\"><em><strong>Scenic Rights is the audiovisual co-agency of Walkabout Literary Agency.\u00a0<\/strong><\/em><\/p>\r\nAnna Bonacina is an Italian author who holds a degree in Foreign Languages and Literatures and a PhD in Comparative Literature. She currently balances her career as a writer with her role as a librarian.\r\n\r\nFurthermore, Bonacina contributes to various media outlets, including writing articles on children's literature for the magazine <em>Il Pepeverde,<\/em> and publishing her own stories in <em>Intimit\u00e0<\/em> magazine.\r\n\r\nHer literary works are distinguished by a refined sense of humor, combined with the development of nuanced characters, with whom readers can readily identify.\r\n\r\n&nbsp;\r\n\r\n<strong>RELEVANT INFORMATION <\/strong>\r\n\r\nHer story titled <em>\"L'amore \u00e8 un herone azzurro\"<\/em> (in English, <em>\"Love Is a Blue Heron\"<\/em>) was selected as one of the <strong>finalists<\/strong> for the <strong>\"Mangia, Scrivi, Eataly!\" award,<\/strong> a competition organized by Eataly and the Holden School.\r\n\r\nHer short story <em>\"Sei cose impossibili prima di colazione\"<\/em> (in English, <em>\"Six Impossible Things Before Breakfast\"<\/em>), was set to music by the esteemed Italian composer Marco Beretta and adapted into a play.","_thumbnail_id":23593,"autor__galeria_archivos":"","idauthor":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Anna Bonacina - Scenic\u00a0Rights<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.scenicrights.com\/en\/author\/anna-bonacina\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anna Bonacina - Scenic\u00a0Rights\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.scenicrights.com\/en\/author\/anna-bonacina\/\" \/>\n<meta property=\"og:site_name\" content=\"Scenic\u00a0Rights\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-19T00:00:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2024\/02\/ANNA-BONACINA.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/en\\\/author\\\/anna-bonacina\\\/\",\"url\":\"https:\\\/\\\/www.scenicrights.com\\\/en\\\/author\\\/anna-bonacina\\\/\",\"name\":\"Anna Bonacina - Scenic\u00a0Rights\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/en\\\/author\\\/anna-bonacina\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/en\\\/author\\\/anna-bonacina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.scenicrights.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/ANNA-BONACINA.webp\",\"datePublished\":\"2024-02-23T11:54:26+00:00\",\"dateModified\":\"2024-04-19T00:00:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/en\\\/author\\\/anna-bonacina\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.scenicrights.com\\\/en\\\/author\\\/anna-bonacina\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/en\\\/author\\\/anna-bonacina\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.scenicrights.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/ANNA-BONACINA.webp\",\"contentUrl\":\"https:\\\/\\\/www.scenicrights.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/ANNA-BONACINA.webp\",\"width\":480,\"height\":360},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/en\\\/author\\\/anna-bonacina\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.scenicrights.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Anna Bonacina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.scenicrights.com\\\/en\\\/\",\"name\":\"Scenic\u00a0Rights\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.scenicrights.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/en\\\/#organization\",\"name\":\"Scenic\u00a0Rights\",\"url\":\"https:\\\/\\\/www.scenicrights.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.scenicrights.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logo-horizontal-web.png\",\"contentUrl\":\"https:\\\/\\\/www.scenicrights.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logo-horizontal-web.png\",\"width\":644,\"height\":225,\"caption\":\"Scenic\u00a0Rights\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Anna Bonacina - Scenic\u00a0Rights","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.scenicrights.com\/en\/author\/anna-bonacina\/","og_locale":"en_US","og_type":"article","og_title":"Anna Bonacina - Scenic\u00a0Rights","og_url":"https:\/\/www.scenicrights.com\/en\/author\/anna-bonacina\/","og_site_name":"Scenic\u00a0Rights","article_modified_time":"2024-04-19T00:00:54+00:00","og_image":[{"width":480,"height":360,"url":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2024\/02\/ANNA-BONACINA.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.scenicrights.com\/en\/author\/anna-bonacina\/","url":"https:\/\/www.scenicrights.com\/en\/author\/anna-bonacina\/","name":"Anna Bonacina - Scenic\u00a0Rights","isPartOf":{"@id":"https:\/\/www.scenicrights.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.scenicrights.com\/en\/author\/anna-bonacina\/#primaryimage"},"image":{"@id":"https:\/\/www.scenicrights.com\/en\/author\/anna-bonacina\/#primaryimage"},"thumbnailUrl":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2024\/02\/ANNA-BONACINA.webp","datePublished":"2024-02-23T11:54:26+00:00","dateModified":"2024-04-19T00:00:54+00:00","breadcrumb":{"@id":"https:\/\/www.scenicrights.com\/en\/author\/anna-bonacina\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.scenicrights.com\/en\/author\/anna-bonacina\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.scenicrights.com\/en\/author\/anna-bonacina\/#primaryimage","url":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2024\/02\/ANNA-BONACINA.webp","contentUrl":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2024\/02\/ANNA-BONACINA.webp","width":480,"height":360},{"@type":"BreadcrumbList","@id":"https:\/\/www.scenicrights.com\/en\/author\/anna-bonacina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.scenicrights.com\/en\/"},{"@type":"ListItem","position":2,"name":"Anna Bonacina"}]},{"@type":"WebSite","@id":"https:\/\/www.scenicrights.com\/en\/#website","url":"https:\/\/www.scenicrights.com\/en\/","name":"Scenic\u00a0Rights","description":"","publisher":{"@id":"https:\/\/www.scenicrights.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.scenicrights.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.scenicrights.com\/en\/#organization","name":"Scenic\u00a0Rights","url":"https:\/\/www.scenicrights.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.scenicrights.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2023\/07\/logo-horizontal-web.png","contentUrl":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2023\/07\/logo-horizontal-web.png","width":644,"height":225,"caption":"Scenic\u00a0Rights"},"image":{"@id":"https:\/\/www.scenicrights.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.scenicrights.com\/en\/wp-json\/wp\/v2\/autor\/23595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.scenicrights.com\/en\/wp-json\/wp\/v2\/autor"}],"about":[{"href":"https:\/\/www.scenicrights.com\/en\/wp-json\/wp\/v2\/types\/autor"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.scenicrights.com\/en\/wp-json\/wp\/v2\/media\/23593"}],"wp:attachment":[{"href":"https:\/\/www.scenicrights.com\/en\/wp-json\/wp\/v2\/media?parent=23595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}