{"id":18468,"date":"2023-09-13T14:39:51","date_gmt":"2023-09-13T14:39:51","guid":{"rendered":"https:\/\/pre.scenicrights.com\/projects\/aurelia-villalba-abogada-de-familia\/"},"modified":"2024-04-02T08:04:49","modified_gmt":"2024-04-02T08:04:49","slug":"aurelia-villalba-abogada-de-familia","status":"publish","type":"articulo","link":"https:\/\/www.scenicrights.com\/es\/projects\/aurelia-villalba-abogada-de-familia\/","title":{"rendered":"Aurelia Villalba: Abogada de familia"},"template":"","art_tag":[431,1255,1257,1274,461,476,496,1267,514],"genero":[8],"licencia":[17],"localizacion":[],"produccion":[],"subgenero":[62,1272],"tipo":[5],"class_list":["post-18468","articulo","type-articulo","status-publish","has-post-thumbnail","hentry","art_tag-familia-disfuncional","art_tag-hechos-reales","art_tag-justicia","art_tag-legal","art_tag-maternidad","art_tag-paternidad","art_tag-rivalidad","art_tag-roles-de-genero","art_tag-superacion","genero-comedia","licencia-propia","subgenero-erotico","subgenero-womens-fiction","tipo-proyecto"],"acf":{"generos_tax":[8],"subgeneros_tax":[62,1272],"tipo_tax":[5],"tags_tax":[1274,431,461,1267,496,1257,1255,514,476],"produccion_tax":false,"licencia_tax":17,"localizacion_tax":false,"articulo__titulo_extendido":"","articulo__extracto":"","articulo__contenido":"<p align=\"right\"><strong><em>No todo lo que cuenta es cierto, pero TODO es verdad...<\/em><\/strong><\/p>\r\nAurelia Villalba siempre pens\u00f3 que ser\u00eda deportista profesional, pero acab\u00f3 convirti\u00e9ndose en abogada especialista en derecho de familia. Se conforma con subir y bajar, cada ma\u00f1ana, los 9 pisos de su edificio durante 30 minutos. Es muy atractiva, est\u00e1 soltera y tiene un hijo, Ram\u00f3n, fruto de una noche de locura con un ex-tenista. Ante la falta de tiempo para conciliar la vida laboral con la familiar, Ram\u00f3n vive con su padre pr\u00e1cticamente desde que naci\u00f3, pero Aurelia se encarga de pagar su manutenci\u00f3n.\r\n\r\nAurelia nunca conoci\u00f3 a su madre, y su padre, Alfredo, le cuenta, cada vez con menos convicci\u00f3n, que ella muri\u00f3 durante el parto. No fuma ni bebe y tampoco sabe cocinar. No tiene ni WhatsApp ni Facebook, la \u00fanica red social que utiliza es para tener encuentros sexuales espor\u00e1dicos con hombres an\u00f3nimos. Es una de las mejores abogadas de la ciudad, su nombre es una instituci\u00f3n en el sector y no hay caso que se le resista. Tiene su propio despacho, en el que trabaja un ecl\u00e9ctico grupo siempre a sus \u00f3rdenes. Entre ellos, est\u00e1 el padre de Aurelia, un hombre que tiene muy pocos escr\u00fapulos para investigar a cualquier sujeto y sacar informaci\u00f3n de debajo de las piedras.\r\n\r\nA lo largo de la historia, Aurelia va resolviendo diferentes casos, como el de una mujer transexual que se enfrenta al rechazo de sus hijas; o un un padre capaz de todo para evitar que su hija se case con su prometido; o el de una joven de 25 a\u00f1os reclamando la paternidad de un poderoso empresario de la ciudad. Tras resolver el \u00faltimo caso, Aurelia Villalba recibe una llamada. Es de la comisar\u00eda, donde reclaman su presencia. All\u00ed, un joven de 19 a\u00f1os pide su defensa tras ser acusado de asesinar al juez que le hab\u00eda trastocado su vida en el juicio del divorcio de sus padres.\r\n\r\nA lo largo de las p\u00e1ginas, la protagonista se enfrentar\u00e1 a grandes casos relacionados con demandas de paternidad, custodias compartidas o pensiones compensatorias. Historias divertidas, locas y frescas que muestran la \u201cjungla\u201d del mundo de los divorcios y sus efectos.\r\n\r\n&nbsp;\r\n\r\n<strong>DATOS RELEVANTES: <\/strong>Luis Zarraluqui es abogado y escritor.<em> En Aurelia Villalba. Abogada de familia,<\/em> Zarraluqui toma como referencia algunos de los casos reales m\u00e1s impactantes que ha llevado durante los m\u00e1s de 30 a\u00f1os de ejercicio de profesi\u00f3n, lo que hace que la trama tenga un gran componente de realidad.\r\n\r\nAurelia Villalba. Abogada de familia cuenta con un gran potencial audiovisual para ser adaptada a serie de TV. El autor ha desarrollado trama suficiente para crear una continuidad y se encuentra escribiendo las dos pr\u00f3ximas entregas de la saga a la que pertenecer\u00e1. tiene los elementos necesarios para desarrollar nuevos casos. Su protagonista, Aurelia, es una mujer valiente y con un potente arco argumental.\r\n\r\n&nbsp;\r\n\r\nLa cr\u00edtica ha dicho:\r\n\r\n\u201cEl abogado ficciona algunos sonados casos que ha llevado su bufete, por donde pasan grandes fortunas, futbolistas y hasta ministros\u2026 En el despacho de Zarraluqui se divorcia la jet.\u201d <em>El Mundo<\/em>.\r\n\r\n\u201cUna novela que habla de la vida personal de un abogado, de la vida en el despacho, y de los casos que mezclan lo profesional con lo personal\u201d <em>Cope<\/em>.\r\n\r\n\u201cZarraluqui analiza muy bien las estrategias de los abogados y la psicolog\u00eda de los clientes.\u201d <em>Amazon<\/em>\r\n\r\n&nbsp;\r\n\r\n<strong>POTENCIAL AUDIOVISUAL<\/strong>: Serie TV, Miniserie, Film, TV Movie.\r\n\r\n<strong>IDIOMAS DISPONIBLES<\/strong>: Espa\u00f1ol.","articulo__autor":[2069],"_thumbnail_id":11380,"articulo__featured_gallery":"","articulo__galeria_archivos":"","articulo__fecha_de_publicacion":"","articulo__idiomas":"","articulo__dossier":11386,"idarticle":1511},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aurelia Villalba: Abogada de familia - Scenic\u00a0Rights<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.scenicrights.com\/es\/projects\/aurelia-villalba-abogada-de-familia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aurelia Villalba: Abogada de familia - Scenic\u00a0Rights\" \/>\n<meta property=\"og:description\" content=\"No todo lo que cuenta es cierto, pero TODO es verdad&#8230; Aurelia Villalba siempre pens&oacute; que ser&iacute;a deportista profesional, pero acab&oacute; convirti&eacute;ndose en abogada especialista en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.scenicrights.com\/es\/projects\/aurelia-villalba-abogada-de-familia\/\" \/>\n<meta property=\"og:site_name\" content=\"Scenic\u00a0Rights\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-02T08:04:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2023\/09\/L4C5Io0qhE2r4EbeJ1ShMg.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"873\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/projects\\\/aurelia-villalba-abogada-de-familia\\\/\",\"url\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/projects\\\/aurelia-villalba-abogada-de-familia\\\/\",\"name\":\"Aurelia Villalba: Abogada de familia - Scenic\u00a0Rights\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/projects\\\/aurelia-villalba-abogada-de-familia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/projects\\\/aurelia-villalba-abogada-de-familia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.scenicrights.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/L4C5Io0qhE2r4EbeJ1ShMg.jpg\",\"datePublished\":\"2023-09-13T14:39:51+00:00\",\"dateModified\":\"2024-04-02T08:04:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/projects\\\/aurelia-villalba-abogada-de-familia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/projects\\\/aurelia-villalba-abogada-de-familia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/projects\\\/aurelia-villalba-abogada-de-familia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.scenicrights.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/L4C5Io0qhE2r4EbeJ1ShMg.jpg\",\"contentUrl\":\"https:\\\/\\\/www.scenicrights.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/L4C5Io0qhE2r4EbeJ1ShMg.jpg\",\"width\":600,\"height\":873},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/projects\\\/aurelia-villalba-abogada-de-familia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aurelia Villalba: Abogada de familia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/\",\"name\":\"Scenic\u00a0Rights\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/#organization\",\"name\":\"Scenic\u00a0Rights\",\"url\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.scenicrights.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logo-horizontal-web.png\",\"contentUrl\":\"https:\\\/\\\/www.scenicrights.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logo-horizontal-web.png\",\"width\":644,\"height\":225,\"caption\":\"Scenic\u00a0Rights\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aurelia Villalba: Abogada de familia - Scenic\u00a0Rights","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.scenicrights.com\/es\/projects\/aurelia-villalba-abogada-de-familia\/","og_locale":"es_ES","og_type":"article","og_title":"Aurelia Villalba: Abogada de familia - Scenic\u00a0Rights","og_description":"No todo lo que cuenta es cierto, pero TODO es verdad&#8230; Aurelia Villalba siempre pens&oacute; que ser&iacute;a deportista profesional, pero acab&oacute; convirti&eacute;ndose en abogada especialista en [&hellip;]","og_url":"https:\/\/www.scenicrights.com\/es\/projects\/aurelia-villalba-abogada-de-familia\/","og_site_name":"Scenic\u00a0Rights","article_modified_time":"2024-04-02T08:04:49+00:00","og_image":[{"width":600,"height":873,"url":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2023\/09\/L4C5Io0qhE2r4EbeJ1ShMg.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.scenicrights.com\/es\/projects\/aurelia-villalba-abogada-de-familia\/","url":"https:\/\/www.scenicrights.com\/es\/projects\/aurelia-villalba-abogada-de-familia\/","name":"Aurelia Villalba: Abogada de familia - Scenic\u00a0Rights","isPartOf":{"@id":"https:\/\/www.scenicrights.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.scenicrights.com\/es\/projects\/aurelia-villalba-abogada-de-familia\/#primaryimage"},"image":{"@id":"https:\/\/www.scenicrights.com\/es\/projects\/aurelia-villalba-abogada-de-familia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2023\/09\/L4C5Io0qhE2r4EbeJ1ShMg.jpg","datePublished":"2023-09-13T14:39:51+00:00","dateModified":"2024-04-02T08:04:49+00:00","breadcrumb":{"@id":"https:\/\/www.scenicrights.com\/es\/projects\/aurelia-villalba-abogada-de-familia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.scenicrights.com\/es\/projects\/aurelia-villalba-abogada-de-familia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.scenicrights.com\/es\/projects\/aurelia-villalba-abogada-de-familia\/#primaryimage","url":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2023\/09\/L4C5Io0qhE2r4EbeJ1ShMg.jpg","contentUrl":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2023\/09\/L4C5Io0qhE2r4EbeJ1ShMg.jpg","width":600,"height":873},{"@type":"BreadcrumbList","@id":"https:\/\/www.scenicrights.com\/es\/projects\/aurelia-villalba-abogada-de-familia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.scenicrights.com\/es\/"},{"@type":"ListItem","position":2,"name":"Aurelia Villalba: Abogada de familia"}]},{"@type":"WebSite","@id":"https:\/\/www.scenicrights.com\/es\/#website","url":"https:\/\/www.scenicrights.com\/es\/","name":"Scenic\u00a0Rights","description":"","publisher":{"@id":"https:\/\/www.scenicrights.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.scenicrights.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.scenicrights.com\/es\/#organization","name":"Scenic\u00a0Rights","url":"https:\/\/www.scenicrights.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.scenicrights.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2023\/07\/logo-horizontal-web.png","contentUrl":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2023\/07\/logo-horizontal-web.png","width":644,"height":225,"caption":"Scenic\u00a0Rights"},"image":{"@id":"https:\/\/www.scenicrights.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/articulo\/18468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/articulo"}],"about":[{"href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/types\/articulo"}],"acf:post":[{"embeddable":true,"href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/autor\/2069"}],"acf:term":[{"embeddable":true,"taxonomy":"licencia","href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/licencia\/17"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/art_tag\/476"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/art_tag\/514"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/art_tag\/1255"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/art_tag\/1257"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/art_tag\/496"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/art_tag\/1267"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/art_tag\/461"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/art_tag\/431"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/art_tag\/1274"},{"embeddable":true,"taxonomy":"tipo","href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/tipo\/5"},{"embeddable":true,"taxonomy":"subgenero","href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/subgenero\/1272"},{"embeddable":true,"taxonomy":"subgenero","href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/subgenero\/62"},{"embeddable":true,"taxonomy":"genero","href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/genero\/8"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/media\/11380"}],"wp:attachment":[{"href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/media?parent=18468"}],"wp:term":[{"taxonomy":"art_tag","embeddable":true,"href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/art_tag?post=18468"},{"taxonomy":"genero","embeddable":true,"href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/genero?post=18468"},{"taxonomy":"licencia","embeddable":true,"href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/licencia?post=18468"},{"taxonomy":"localizacion","embeddable":true,"href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/localizacion?post=18468"},{"taxonomy":"produccion","embeddable":true,"href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/produccion?post=18468"},{"taxonomy":"subgenero","embeddable":true,"href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/subgenero?post=18468"},{"taxonomy":"tipo","embeddable":true,"href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/tipo?post=18468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}