{"id":18649,"date":"2023-09-13T14:48:18","date_gmt":"2023-09-13T14:48:18","guid":{"rendered":"https:\/\/pre.scenicrights.com\/projects\/amor-tres-delicias\/"},"modified":"2024-04-02T08:03:31","modified_gmt":"2024-04-02T08:03:31","slug":"amor-tres-delicias","status":"publish","type":"articulo","link":"https:\/\/www.scenicrights.com\/es\/projects\/amor-tres-delicias\/","title":{"rendered":"Amor tres delicias"},"template":"","art_tag":[363,562,606,430,1275,514],"genero":[8],"licencia":[17],"localizacion":[],"produccion":[],"subgenero":[1355,1318],"tipo":[5],"class_list":["post-18649","articulo","type-articulo","status-publish","has-post-thumbnail","hentry","art_tag-amor","art_tag-cultura","art_tag-empoderamiento","art_tag-familia","art_tag-identidad","art_tag-superacion","genero-comedia","licencia-propia","subgenero-new-adult","subgenero-romance","tipo-proyecto"],"acf":{"generos_tax":[8],"subgeneros_tax":[1318,1355],"tipo_tax":[5],"tags_tax":[363,430,514,562,606,1275],"produccion_tax":false,"licencia_tax":17,"localizacion_tax":false,"articulo__titulo_extendido":"","articulo__extracto":"","articulo__contenido":"<p align=\"right\"><strong><em>Cuando dos mundos (literalmente) chocan.<\/em><\/strong><\/p>\r\nNina Chou, una joven madrile\u00f1a de origen chino, lleva un tiempo sintiendo que debe encontrarse a s\u00ed misma en lugar de hacer todo lo que su tradicional familia espera que haga. Decidida, sat\u00edrica y un poco desastre, Nina vive en Madrid junto a sus padres, que no ven el momento en que su hija se case, por lo que le organizan un sinf\u00edn de citas a ciegas, con j\u00f3venes y mod\u00e9licos pretendientes chinos, a las que Nina acude de mala gana.\r\n\r\nSin embargo, Nina interpreta el papel de buena hija: trabaja de noche en el restaurante chino de sus padres, y de d\u00eda en la peluquer\u00eda de su hermana... o eso es lo que hace creer a todos.\r\n\r\nSu gran secreto es que se escapa para cursar qu\u00edmica en la universidad, enga\u00f1ando descaradamente a sus padres.\r\n\r\nEn este contexto aparece Rub\u00e9n, un matem\u00e1tico <em>friki<\/em> del que se ha colgado y que le har\u00e1 ver, en la complicada ecuaci\u00f3n que supone el d\u00eda a d\u00eda de una primera relaci\u00f3n de amor, lo mejor y lo peor de sus tan dispares culturas.\r\nSuperando prejucios raciales y culturales Nina deber\u00e1 encontrar la manera de cumplir sus propios sue\u00f1os, sin decepcionar a sus padres.\r\n\r\n&nbsp;\r\n\r\n<strong>DATOS RELEVANTES:<\/strong> Una comedia rom\u00e1ntica fresca y amable que cabalga entre <em>To All the Boys I\u2019ve Loved Before <\/em>y <em>Ocho apellidos vascos<\/em>, <em>Amor tres delicias<\/em> nos permite reflexionar sobre la vida de una familia china tradicional viviendo en Espa\u00f1a y, en particular, sobre la lucha de una joven china que se enfrenta a estas dos culturas tan diferentes a las puertas de entrar en la vida adulta.\r\n\r\nAmelia Chardin hace un salto m\u00e1s en su carrera literaria, como joven promesa que no duda en imprimir en su obra su sello personal y del que tantas lectoras ya se han hecho fieles seguidoras.\r\n\r\n&nbsp;\r\n\r\nLo que ha dicho la cr\u00edtica:\r\n\r\n\u201cNos ense\u00f1a la cultura china (y asi\u00e1tica) desde dentro, de una manera amable, humor\u00edstica y, sobre todo, cari\u00f1osa.\u201d <em>Goodreads<\/em>\r\n\r\n\u201cTe emocionar\u00e1, te divertir\u00e1, te har\u00e1 so\u00f1ar, [\u2026] y te sentir\u00e1s identificada con su protagonista.\u201d<em> Libros recomendados <\/em>(blog literario)\r\n\r\n&nbsp;\r\n\r\n<strong>POTENCIAL AUDIOVISUAL: <\/strong>Serie TV, Miniserie, Film, TV Movie.\r\n\r\n<strong>IDIOMAS DISPONIBLES: <\/strong>Espa\u00f1ol<strong>.<\/strong>","articulo__autor":[2453],"_thumbnail_id":12656,"articulo__featured_gallery":"","articulo__galeria_archivos":"","articulo__fecha_de_publicacion":"","articulo__idiomas":"","articulo__dossier":"","idarticle":1692},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Amor tres delicias - Scenic\u00a0Rights<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.scenicrights.com\/es\/projects\/amor-tres-delicias\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Amor tres delicias - Scenic\u00a0Rights\" \/>\n<meta property=\"og:description\" content=\"Cuando dos mundos (literalmente) chocan. &nbsp; Nina Chou, una joven madrile&ntilde;a de origen chino, lleva un tiempo sintiendo que debe encontrarse a s&iacute; misma en lugar [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.scenicrights.com\/es\/projects\/amor-tres-delicias\/\" \/>\n<meta property=\"og:site_name\" content=\"Scenic\u00a0Rights\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-02T08:03:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2023\/09\/dQrIFEtXOUG6Rauq7cyO2Q.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1352\" \/>\n\t<meta property=\"og:image:height\" content=\"2048\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/projects\\\/amor-tres-delicias\\\/\",\"url\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/projects\\\/amor-tres-delicias\\\/\",\"name\":\"Amor tres delicias - Scenic\u00a0Rights\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/projects\\\/amor-tres-delicias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/projects\\\/amor-tres-delicias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.scenicrights.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/dQrIFEtXOUG6Rauq7cyO2Q.jpg\",\"datePublished\":\"2023-09-13T14:48:18+00:00\",\"dateModified\":\"2024-04-02T08:03:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/projects\\\/amor-tres-delicias\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/projects\\\/amor-tres-delicias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/projects\\\/amor-tres-delicias\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.scenicrights.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/dQrIFEtXOUG6Rauq7cyO2Q.jpg\",\"contentUrl\":\"https:\\\/\\\/www.scenicrights.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/dQrIFEtXOUG6Rauq7cyO2Q.jpg\",\"width\":1352,\"height\":2048},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/projects\\\/amor-tres-delicias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Amor tres delicias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/\",\"name\":\"Scenic\u00a0Rights\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/#organization\",\"name\":\"Scenic\u00a0Rights\",\"url\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.scenicrights.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logo-horizontal-web.png\",\"contentUrl\":\"https:\\\/\\\/www.scenicrights.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logo-horizontal-web.png\",\"width\":644,\"height\":225,\"caption\":\"Scenic\u00a0Rights\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Amor tres delicias - Scenic\u00a0Rights","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.scenicrights.com\/es\/projects\/amor-tres-delicias\/","og_locale":"es_ES","og_type":"article","og_title":"Amor tres delicias - Scenic\u00a0Rights","og_description":"Cuando dos mundos (literalmente) chocan. &nbsp; Nina Chou, una joven madrile&ntilde;a de origen chino, lleva un tiempo sintiendo que debe encontrarse a s&iacute; misma en lugar [&hellip;]","og_url":"https:\/\/www.scenicrights.com\/es\/projects\/amor-tres-delicias\/","og_site_name":"Scenic\u00a0Rights","article_modified_time":"2024-04-02T08:03:31+00:00","og_image":[{"width":1352,"height":2048,"url":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2023\/09\/dQrIFEtXOUG6Rauq7cyO2Q.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.scenicrights.com\/es\/projects\/amor-tres-delicias\/","url":"https:\/\/www.scenicrights.com\/es\/projects\/amor-tres-delicias\/","name":"Amor tres delicias - Scenic\u00a0Rights","isPartOf":{"@id":"https:\/\/www.scenicrights.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.scenicrights.com\/es\/projects\/amor-tres-delicias\/#primaryimage"},"image":{"@id":"https:\/\/www.scenicrights.com\/es\/projects\/amor-tres-delicias\/#primaryimage"},"thumbnailUrl":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2023\/09\/dQrIFEtXOUG6Rauq7cyO2Q.jpg","datePublished":"2023-09-13T14:48:18+00:00","dateModified":"2024-04-02T08:03:31+00:00","breadcrumb":{"@id":"https:\/\/www.scenicrights.com\/es\/projects\/amor-tres-delicias\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.scenicrights.com\/es\/projects\/amor-tres-delicias\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.scenicrights.com\/es\/projects\/amor-tres-delicias\/#primaryimage","url":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2023\/09\/dQrIFEtXOUG6Rauq7cyO2Q.jpg","contentUrl":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2023\/09\/dQrIFEtXOUG6Rauq7cyO2Q.jpg","width":1352,"height":2048},{"@type":"BreadcrumbList","@id":"https:\/\/www.scenicrights.com\/es\/projects\/amor-tres-delicias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.scenicrights.com\/es\/"},{"@type":"ListItem","position":2,"name":"Amor tres delicias"}]},{"@type":"WebSite","@id":"https:\/\/www.scenicrights.com\/es\/#website","url":"https:\/\/www.scenicrights.com\/es\/","name":"Scenic\u00a0Rights","description":"","publisher":{"@id":"https:\/\/www.scenicrights.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.scenicrights.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.scenicrights.com\/es\/#organization","name":"Scenic\u00a0Rights","url":"https:\/\/www.scenicrights.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.scenicrights.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2023\/07\/logo-horizontal-web.png","contentUrl":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2023\/07\/logo-horizontal-web.png","width":644,"height":225,"caption":"Scenic\u00a0Rights"},"image":{"@id":"https:\/\/www.scenicrights.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/articulo\/18649","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/articulo"}],"about":[{"href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/types\/articulo"}],"acf:post":[{"embeddable":true,"href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/autor\/2453"}],"acf:term":[{"embeddable":true,"taxonomy":"licencia","href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/licencia\/17"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/art_tag\/1275"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/art_tag\/606"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/art_tag\/562"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/art_tag\/514"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/art_tag\/430"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/art_tag\/363"},{"embeddable":true,"taxonomy":"tipo","href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/tipo\/5"},{"embeddable":true,"taxonomy":"subgenero","href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/subgenero\/1355"},{"embeddable":true,"taxonomy":"subgenero","href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/subgenero\/1318"},{"embeddable":true,"taxonomy":"genero","href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/genero\/8"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/media\/12656"}],"wp:attachment":[{"href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/media?parent=18649"}],"wp:term":[{"taxonomy":"art_tag","embeddable":true,"href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/art_tag?post=18649"},{"taxonomy":"genero","embeddable":true,"href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/genero?post=18649"},{"taxonomy":"licencia","embeddable":true,"href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/licencia?post=18649"},{"taxonomy":"localizacion","embeddable":true,"href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/localizacion?post=18649"},{"taxonomy":"produccion","embeddable":true,"href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/produccion?post=18649"},{"taxonomy":"subgenero","embeddable":true,"href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/subgenero?post=18649"},{"taxonomy":"tipo","embeddable":true,"href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/tipo?post=18649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}