{"id":28278,"date":"2025-09-02T14:29:17","date_gmt":"2025-09-02T14:29:17","guid":{"rendered":"https:\/\/www.scenicrights.com\/?post_type=articulo&#038;p=28278"},"modified":"2026-01-23T13:53:00","modified_gmt":"2026-01-23T13:53:00","slug":"la-noche-sera-negra-y-blanca","status":"publish","type":"articulo","link":"https:\/\/www.scenicrights.com\/es\/projects\/la-noche-sera-negra-y-blanca\/","title":{"rendered":"La noche ser\u00e1 negra y blanca"},"template":"","art_tag":[363,1244,403,561,431,461,572,589,476,488,524],"genero":[7],"licencia":[17],"localizacion":[],"produccion":[],"subgenero":[69,1272],"tipo":[5],"class_list":["post-28278","articulo","type-articulo","status-publish","has-post-thumbnail","hentry","art_tag-amor","art_tag-conflicto-generacional-2","art_tag-crisis-existencial","art_tag-estados-unidos","art_tag-familia-disfuncional","art_tag-maternidad","art_tag-mexico","art_tag-pasado","art_tag-paternidad","art_tag-redencion","art_tag-vejez","genero-drama","licencia-propia","subgenero-melodrama","subgenero-womens-fiction","tipo-proyecto"],"acf":{"generos_tax":[7],"subgeneros_tax":[69,1272],"tipo_tax":[5],"tags_tax":[363,1244,403,561,431,461,572,589,476,488,524],"produccion_tax":false,"licencia_tax":17,"localizacion_tax":false,"articulo__titulo_extendido":"","articulo__extracto":"","articulo__contenido":"<strong><em>Al recibir una llamada de su padre para reencontrarse con \u00e9l, una periodista mexicana reconstruye la historia de su familia, marcada por el trauma y la violencia heredada. En el proceso, descubre en la escritura un camino hacia la sanaci\u00f3n y la redenci\u00f3n personal. Un drama familiar profundo y conmovedor, desde la reconocida pluma de Socorro Venegas.<\/em><\/strong>\r\n\r\n&nbsp;\r\n\r\nAndrea, una periodista mexicana, recibe una llamada inesperada de su padre Bernardo despu\u00e9s de diez a\u00f1os de ausencia. \u00c9l le pide que viaje a Denver para verlo, lo que la sumerge en recuerdos de una infancia marcada por el alcoholismo de su padre y la muerte accidental de su hermano menor Gabriel. Su madre, fr\u00eda y distante, le entrega ropa para que se la lleve, insinuando que su padre est\u00e1 cerca de la muerte.\r\n\r\nAntes de viajar a Estados Unidos, Andrea visita a su abuela Paz en San Luis Potos\u00ed para entender el pasado de su padre. La abuela le revela c\u00f3mo Bernardo fue traumatizado en su ni\u00f1ez por su propio padre, un matarife violento que lo obligaba a participar en sacrificios de animales. Estas experiencias explicar\u00edan su posterior alcoholismo y su incapacidad para formar una familia estable.\r\n\r\nEn paralelo, Andrea mantiene conversaciones con Eugenio Mill\u00e1, un escritor enfermo de c\u00e1ncer que la anima a escribir sobre su historia familiar como forma de catarsis. Mill\u00e1, un hombre c\u00ednico pero perspicaz, comparte con ella sus propias reflexiones sobre el amor y la muerte mientras lucha contra su enfermedad terminal.\r\n\r\nAl llegar a Denver, Andrea encuentra a su padre envejecido y fr\u00e1gil, pero sobrio. Durante su encuentro, reviven viejos recuerdos, particularmente su mutua afici\u00f3n por las pel\u00edculas de Bruce Lee, que representan los pocos momentos felices de su infancia. Bernardo confiesa haber trabajado como matarife en Estados Unidos, repitiendo involuntariamente el ciclo de violencia de su familia. Andrea le entrega un cuento que escribi\u00f3 sobre su vida, imaginando su juventud traum\u00e1tica. En un momento de conexi\u00f3n, \u00e9l le canta una canci\u00f3n de su ni\u00f1ez.\r\n\r\nDe regreso en M\u00e9xico, Andrea entrega sus escritos a Mill\u00e1, quien los recibe como testimonio de un dolor transformado en arte. La novela termina con esta entrega simb\u00f3lica, donde las palabras escritas parecen fundirse con la enfermedad del escritor, sugiriendo que tanto el arte como la vida son formas de enfrentar la p\u00e9rdida y el sufrimiento heredado.\r\n\r\n&nbsp;\r\n\r\n<strong>DATOS RELEVANTES:<\/strong> Socorro Venegas es una escritora mexicana de narrativa y poes\u00eda, ganadora del <strong>Premio de Poes\u00eda y Cuento Benem\u00e9rito de Am\u00e9rica<\/strong> y del <strong>Premio de Novela Carlos Fuentes<\/strong>, este \u00faltimo con<em> La noche ser\u00e1 negra y blanca<\/em>.\r\n\r\nEn <em>La noche ser\u00e1 negra y blanca<\/em>, la escritora construye una trama ce\u00f1ida en torno a la historia de una familia atravesada por el trauma y la violencia, pero que, en el fondo y de una manera muy particular, desprende amor. Los personajes son complejos y variados, ninguno est\u00e1 encasillado en un perfil. Es un libro intenso, conmovedor y con toques de humor.\r\n\r\nLa novela tiene una puesta en escena sensible y po\u00e9tica, al estilo de <em>Aftersun<\/em> o <em>Roma<\/em>, que explore el trauma, la memoria y la redenci\u00f3n a trav\u00e9s del arte.\r\n\r\n&nbsp;\r\n\r\n<strong>POTENCIAL AUDIOVISUAL:<\/strong> Serie TV, Miniserie, Film, TV Film.\r\n\r\n<strong>IDIOMAS DISPONIBLES:<\/strong> Espa\u00f1ol.","articulo__autor":[30149],"_thumbnail_id":28279,"articulo__featured_gallery":"","articulo__galeria_archivos":"","articulo__fecha_de_publicacion":"","articulo__idiomas":"","articulo__dossier":"","idarticle":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La noche ser\u00e1 negra y blanca - Scenic\u00a0Rights<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.scenicrights.com\/es\/projects\/la-noche-sera-negra-y-blanca\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La noche ser\u00e1 negra y blanca - Scenic\u00a0Rights\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.scenicrights.com\/es\/projects\/la-noche-sera-negra-y-blanca\/\" \/>\n<meta property=\"og:site_name\" content=\"Scenic\u00a0Rights\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-23T13:53:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2025\/09\/Cubierta_La_noche_sera_negra_y_blanca-768x1212-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"1212\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/projects\\\/la-noche-sera-negra-y-blanca\\\/\",\"url\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/projects\\\/la-noche-sera-negra-y-blanca\\\/\",\"name\":\"La noche ser\u00e1 negra y blanca - Scenic\u00a0Rights\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/projects\\\/la-noche-sera-negra-y-blanca\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/projects\\\/la-noche-sera-negra-y-blanca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.scenicrights.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Cubierta_La_noche_sera_negra_y_blanca-768x1212-1.jpg\",\"datePublished\":\"2025-09-02T14:29:17+00:00\",\"dateModified\":\"2026-01-23T13:53:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/projects\\\/la-noche-sera-negra-y-blanca\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/projects\\\/la-noche-sera-negra-y-blanca\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/projects\\\/la-noche-sera-negra-y-blanca\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.scenicrights.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Cubierta_La_noche_sera_negra_y_blanca-768x1212-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.scenicrights.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Cubierta_La_noche_sera_negra_y_blanca-768x1212-1.jpg\",\"width\":768,\"height\":1212},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/projects\\\/la-noche-sera-negra-y-blanca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La noche ser\u00e1 negra y blanca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/\",\"name\":\"Scenic\u00a0Rights\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/#organization\",\"name\":\"Scenic\u00a0Rights\",\"url\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.scenicrights.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logo-horizontal-web.png\",\"contentUrl\":\"https:\\\/\\\/www.scenicrights.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logo-horizontal-web.png\",\"width\":644,\"height\":225,\"caption\":\"Scenic\u00a0Rights\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La noche ser\u00e1 negra y blanca - Scenic\u00a0Rights","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.scenicrights.com\/es\/projects\/la-noche-sera-negra-y-blanca\/","og_locale":"es_ES","og_type":"article","og_title":"La noche ser\u00e1 negra y blanca - Scenic\u00a0Rights","og_url":"https:\/\/www.scenicrights.com\/es\/projects\/la-noche-sera-negra-y-blanca\/","og_site_name":"Scenic\u00a0Rights","article_modified_time":"2026-01-23T13:53:00+00:00","og_image":[{"width":768,"height":1212,"url":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2025\/09\/Cubierta_La_noche_sera_negra_y_blanca-768x1212-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.scenicrights.com\/es\/projects\/la-noche-sera-negra-y-blanca\/","url":"https:\/\/www.scenicrights.com\/es\/projects\/la-noche-sera-negra-y-blanca\/","name":"La noche ser\u00e1 negra y blanca - Scenic\u00a0Rights","isPartOf":{"@id":"https:\/\/www.scenicrights.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.scenicrights.com\/es\/projects\/la-noche-sera-negra-y-blanca\/#primaryimage"},"image":{"@id":"https:\/\/www.scenicrights.com\/es\/projects\/la-noche-sera-negra-y-blanca\/#primaryimage"},"thumbnailUrl":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2025\/09\/Cubierta_La_noche_sera_negra_y_blanca-768x1212-1.jpg","datePublished":"2025-09-02T14:29:17+00:00","dateModified":"2026-01-23T13:53:00+00:00","breadcrumb":{"@id":"https:\/\/www.scenicrights.com\/es\/projects\/la-noche-sera-negra-y-blanca\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.scenicrights.com\/es\/projects\/la-noche-sera-negra-y-blanca\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.scenicrights.com\/es\/projects\/la-noche-sera-negra-y-blanca\/#primaryimage","url":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2025\/09\/Cubierta_La_noche_sera_negra_y_blanca-768x1212-1.jpg","contentUrl":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2025\/09\/Cubierta_La_noche_sera_negra_y_blanca-768x1212-1.jpg","width":768,"height":1212},{"@type":"BreadcrumbList","@id":"https:\/\/www.scenicrights.com\/es\/projects\/la-noche-sera-negra-y-blanca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.scenicrights.com\/es\/"},{"@type":"ListItem","position":2,"name":"La noche ser\u00e1 negra y blanca"}]},{"@type":"WebSite","@id":"https:\/\/www.scenicrights.com\/es\/#website","url":"https:\/\/www.scenicrights.com\/es\/","name":"Scenic\u00a0Rights","description":"","publisher":{"@id":"https:\/\/www.scenicrights.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.scenicrights.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.scenicrights.com\/es\/#organization","name":"Scenic\u00a0Rights","url":"https:\/\/www.scenicrights.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.scenicrights.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2023\/07\/logo-horizontal-web.png","contentUrl":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2023\/07\/logo-horizontal-web.png","width":644,"height":225,"caption":"Scenic\u00a0Rights"},"image":{"@id":"https:\/\/www.scenicrights.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/articulo\/28278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/articulo"}],"about":[{"href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/types\/articulo"}],"acf:post":[{"embeddable":true,"href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/autor\/30149"}],"acf:term":[{"embeddable":true,"taxonomy":"licencia","href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/licencia\/17"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/art_tag\/524"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/art_tag\/488"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/art_tag\/476"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/art_tag\/589"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/art_tag\/572"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/art_tag\/461"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/art_tag\/431"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/art_tag\/561"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/art_tag\/403"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/art_tag\/1244"},{"embeddable":true,"taxonomy":"art_tag","href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/art_tag\/363"},{"embeddable":true,"taxonomy":"tipo","href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/tipo\/5"},{"embeddable":true,"taxonomy":"subgenero","href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/subgenero\/1272"},{"embeddable":true,"taxonomy":"subgenero","href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/subgenero\/69"},{"embeddable":true,"taxonomy":"genero","href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/genero\/7"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/media\/28279"}],"wp:attachment":[{"href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/media?parent=28278"}],"wp:term":[{"taxonomy":"art_tag","embeddable":true,"href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/art_tag?post=28278"},{"taxonomy":"genero","embeddable":true,"href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/genero?post=28278"},{"taxonomy":"licencia","embeddable":true,"href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/licencia?post=28278"},{"taxonomy":"localizacion","embeddable":true,"href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/localizacion?post=28278"},{"taxonomy":"produccion","embeddable":true,"href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/produccion?post=28278"},{"taxonomy":"subgenero","embeddable":true,"href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/subgenero?post=28278"},{"taxonomy":"tipo","embeddable":true,"href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/tipo?post=28278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}