{"id":1282,"date":"2023-09-12T13:17:06","date_gmt":"2023-09-12T13:17:06","guid":{"rendered":"https:\/\/pre.scenicrights.com\/author\/jose-ignacio-chascas-valenzuela\/"},"modified":"2026-02-09T10:07:01","modified_gmt":"2026-02-09T10:07:01","slug":"jose-ignacio-chascas-valenzuela","status":"publish","type":"autor","link":"https:\/\/www.scenicrights.com\/es\/author\/jose-ignacio-chascas-valenzuela\/","title":{"rendered":"Jos\u00e9 Ignacio (Chascas) Valenzuela"},"template":"","class_list":["post-1282","autor","type-autor","status-publish","has-post-thumbnail","hentry"],"acf":{"autor_contenido":"<p align=\"right\"><strong><em>Scenic Rights is the audiovisual co-agency <\/em><\/strong><strong><em>of Antonia Kerrigan Literary Agency<\/em><\/strong><\/p>\r\n&nbsp;\r\n\r\nJos\u00e9<span lang=\"ES-TRAD\"> Ignacio <\/span><span lang=\"ES-TRAD\">(Chascas)<\/span><span lang=\"ES-TRAD\"> Valenzuela es un escritor y guionista chileno. Su trabajo incluye m\u00e1s de una veintena de libros publicados en diferentes idiomas y exitosas series de televisi\u00f3n.<i> <\/i>Como docente ha impartido clases de guion y escritura creativa en gran parte de Latinoam\u00e9rica, y en universidades de M\u00e9xico, Chile, Estados Unidos, Rep\u00fablica Dominicana y Puerto Rico.<\/span><b><\/b>\r\n\r\nValenzuela es el creador de la exitosa serie de Netflix <i>\u00bfQui\u00e9n mat\u00f3 a Sara?, <\/i>que fue el mejor \u00e9xito de habla no inglesa en la historia de la plataforma en Estados Unidos. Cuenta con m\u00e1<span lang=\"ES-TRAD\">s de treinta novelas publicadas y trece series televisivas y pel<\/span>\u00ed<span lang=\"ES-TRAD\">culas, en Chile, M<\/span>\u00e9<span lang=\"ES-TRAD\">xico,<\/span>\u00a0Estados Unidos\u00a0y Puerto Rico. F<span lang=\"ES-TRAD\">ue seleccionado por la revista<\/span> <i>About.com<\/i> de <i>The New York Times<\/i> <span lang=\"ES-TRAD\">como uno de los diez mejores escritores<\/span>\u00a0j<span lang=\"ES-TRAD\">\u00f3venes<\/span>\u00a0latinoamericanos.\r\n\r\nC<span lang=\"ES-TRAD\">omo guionista ha sido en muchas ocasiones premiado con galardones como<\/span>\u00a0<b><span lang=\"ES-TRAD\">Mejor Guionista del A\u00f1<\/span><\/b><b>o<\/b>\u00a0<span lang=\"ES-TRAD\">por el<\/span>\u00a0<b><span lang=\"ES-TRAD\">Instituto de Comunicaci\u00f3n PROCO<\/span><\/b><b>\u00a0y<\/b><span lang=\"ES-TRAD\"> el<\/span><b>\u00a0<\/b><b><span lang=\"ES-TRAD\">Festival Internacional de cine Diosa de Plata<\/span><\/b><span lang=\"ES-TRAD\">. Fue<\/span>\u00a0<span lang=\"ES-TRAD\">nominado a un <\/span><b>Emmy<\/b><b>\u00a0Award <\/b><span lang=\"ES-TRAD\">por su trabajo como escritor de la serie televisiva<\/span><i> <\/i><i>Amores<\/i><i>.<\/i> <span lang=\"ES-TRAD\">Su telenovela<\/span><i>\u00a0<\/i><span lang=\"ES-TRAD\">La casa de al lado<\/span><i>, <\/i>emitida por Telemundo (el segundo mayor proveedor de contenido en espa\u00f1ol en los Estados Unidos), <span lang=\"ES-TRAD\">obtuvo el galard\u00f3n<\/span>\u00a0<b><i>\u201cBest novela of the Year\u201d<\/i><\/b><i> <\/i><span lang=\"ES-TRAD\">en los <\/span><b>Premios Miami Life<\/b><span lang=\"ES-TRAD\">. Su <\/span>telenovela<i>\u00a0<\/i><span lang=\"ES-TRAD\">Santa Diabla<\/span>, tambi\u00e9n emitida por Telemundo, <span lang=\"ES-TRAD\">recibi\u00f3 la<\/span>\u00a0distinci<span lang=\"ES-TRAD\">\u00f3<\/span>n <b><span lang=\"ES-TRAD\">\"Novela del a\u00f1o\"<\/span><\/b><b><i> <\/i><\/b><span lang=\"ES-TRAD\">en los<\/span><b>\u00a0<\/b><b><span lang=\"ES-TRAD\">Premios Tu Mundo. <\/span><\/b><span lang=\"ES-TRAD\">Otros de sus trabajos como guionista y showrunner son las series Donde hubo fuego, Candy Cruz y Las Hermanas Guerra.<\/span>","_thumbnail_id":1283,"autor__galeria_archivos":"","idauthor":117},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jos\u00e9 Ignacio (Chascas) Valenzuela - Scenic\u00a0Rights<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.scenicrights.com\/es\/author\/jose-ignacio-chascas-valenzuela\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jos\u00e9 Ignacio (Chascas) Valenzuela - Scenic\u00a0Rights\" \/>\n<meta property=\"og:description\" content=\"&nbsp; &nbsp; Scenic Rights is the audiovisual co-agency of Antonia Kerrigan Literary Agency NOTA BIOGR&Aacute;FICA Jos&eacute; Ignacio (Chascas) Valenzuela es un escritor y guionista chileno. Como [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.scenicrights.com\/es\/author\/jose-ignacio-chascas-valenzuela\/\" \/>\n<meta property=\"og:site_name\" content=\"Scenic\u00a0Rights\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-09T10:07:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2023\/09\/SV7B6bePUm0GjiLmTQ.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1067\" \/>\n\t<meta property=\"og:image:height\" content=\"1600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/author\\\/jose-ignacio-chascas-valenzuela\\\/\",\"url\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/author\\\/jose-ignacio-chascas-valenzuela\\\/\",\"name\":\"Jos\u00e9 Ignacio (Chascas) Valenzuela - Scenic\u00a0Rights\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/author\\\/jose-ignacio-chascas-valenzuela\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/author\\\/jose-ignacio-chascas-valenzuela\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.scenicrights.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/SV7B6bePUm0GjiLmTQ.jpg\",\"datePublished\":\"2023-09-12T13:17:06+00:00\",\"dateModified\":\"2026-02-09T10:07:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/author\\\/jose-ignacio-chascas-valenzuela\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/author\\\/jose-ignacio-chascas-valenzuela\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/author\\\/jose-ignacio-chascas-valenzuela\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.scenicrights.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/SV7B6bePUm0GjiLmTQ.jpg\",\"contentUrl\":\"https:\\\/\\\/www.scenicrights.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/SV7B6bePUm0GjiLmTQ.jpg\",\"width\":1067,\"height\":1600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/author\\\/jose-ignacio-chascas-valenzuela\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jos\u00e9 Ignacio (Chascas) Valenzuela\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/\",\"name\":\"Scenic\u00a0Rights\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/#organization\",\"name\":\"Scenic\u00a0Rights\",\"url\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.scenicrights.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logo-horizontal-web.png\",\"contentUrl\":\"https:\\\/\\\/www.scenicrights.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/logo-horizontal-web.png\",\"width\":644,\"height\":225,\"caption\":\"Scenic\u00a0Rights\"},\"image\":{\"@id\":\"https:\\\/\\\/www.scenicrights.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jos\u00e9 Ignacio (Chascas) Valenzuela - Scenic\u00a0Rights","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.scenicrights.com\/es\/author\/jose-ignacio-chascas-valenzuela\/","og_locale":"es_ES","og_type":"article","og_title":"Jos\u00e9 Ignacio (Chascas) Valenzuela - Scenic\u00a0Rights","og_description":"&nbsp; &nbsp; Scenic Rights is the audiovisual co-agency of Antonia Kerrigan Literary Agency NOTA BIOGR&Aacute;FICA Jos&eacute; Ignacio (Chascas) Valenzuela es un escritor y guionista chileno. Como [&hellip;]","og_url":"https:\/\/www.scenicrights.com\/es\/author\/jose-ignacio-chascas-valenzuela\/","og_site_name":"Scenic\u00a0Rights","article_modified_time":"2026-02-09T10:07:01+00:00","og_image":[{"width":1067,"height":1600,"url":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2023\/09\/SV7B6bePUm0GjiLmTQ.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.scenicrights.com\/es\/author\/jose-ignacio-chascas-valenzuela\/","url":"https:\/\/www.scenicrights.com\/es\/author\/jose-ignacio-chascas-valenzuela\/","name":"Jos\u00e9 Ignacio (Chascas) Valenzuela - Scenic\u00a0Rights","isPartOf":{"@id":"https:\/\/www.scenicrights.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.scenicrights.com\/es\/author\/jose-ignacio-chascas-valenzuela\/#primaryimage"},"image":{"@id":"https:\/\/www.scenicrights.com\/es\/author\/jose-ignacio-chascas-valenzuela\/#primaryimage"},"thumbnailUrl":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2023\/09\/SV7B6bePUm0GjiLmTQ.jpg","datePublished":"2023-09-12T13:17:06+00:00","dateModified":"2026-02-09T10:07:01+00:00","breadcrumb":{"@id":"https:\/\/www.scenicrights.com\/es\/author\/jose-ignacio-chascas-valenzuela\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.scenicrights.com\/es\/author\/jose-ignacio-chascas-valenzuela\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.scenicrights.com\/es\/author\/jose-ignacio-chascas-valenzuela\/#primaryimage","url":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2023\/09\/SV7B6bePUm0GjiLmTQ.jpg","contentUrl":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2023\/09\/SV7B6bePUm0GjiLmTQ.jpg","width":1067,"height":1600},{"@type":"BreadcrumbList","@id":"https:\/\/www.scenicrights.com\/es\/author\/jose-ignacio-chascas-valenzuela\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.scenicrights.com\/es\/"},{"@type":"ListItem","position":2,"name":"Jos\u00e9 Ignacio (Chascas) Valenzuela"}]},{"@type":"WebSite","@id":"https:\/\/www.scenicrights.com\/es\/#website","url":"https:\/\/www.scenicrights.com\/es\/","name":"Scenic\u00a0Rights","description":"","publisher":{"@id":"https:\/\/www.scenicrights.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.scenicrights.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.scenicrights.com\/es\/#organization","name":"Scenic\u00a0Rights","url":"https:\/\/www.scenicrights.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.scenicrights.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2023\/07\/logo-horizontal-web.png","contentUrl":"https:\/\/www.scenicrights.com\/wp-content\/uploads\/2023\/07\/logo-horizontal-web.png","width":644,"height":225,"caption":"Scenic\u00a0Rights"},"image":{"@id":"https:\/\/www.scenicrights.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/autor\/1282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/autor"}],"about":[{"href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/types\/autor"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/media\/1283"}],"wp:attachment":[{"href":"https:\/\/www.scenicrights.com\/es\/wp-json\/wp\/v2\/media?parent=1282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}